{"id":15913,"date":"2019-10-18T19:19:06","date_gmt":"2019-10-18T17:19:06","guid":{"rendered":"http:\/\/www.consorziobonifica.it\/palermo2\/archivio_storico\/determina-n-199-dell11-09-2019\/"},"modified":"2020-04-07T14:59:24","modified_gmt":"2020-04-07T12:59:24","slug":"determina-n-199-dell11-09-2019","status":"publish","type":"amm_trasparente","link":"https:\/\/www.consorziobonifica.it\/palermo2\/amm_trasparente\/determina-n-199-dell11-09-2019\/","title":{"rendered":"Determina di approvazione preventivo ed impegno somme, per l&#8217;affidamento della fornitura, nell&#8217;ambito della gara informale, ai sensi dell&#8217;art. 36, comma 2, lettera a), del D.Lgs. n. 50 del 18 aprile 2016 e ss.mm.ii., di gasolio per autotrazione, per l&#8217;azionamneto dei mezzi, per la manutenzione ordinaria, lungo i comprensori irrigui consortili, campagna irrigua 2019, alla ditta Gandolfo s.r.l. CIG: Z8F29A478D."},"content":{"rendered":"<p style=\"text-align: justify;\"><span style=\"font-family: 'times new roman', times; font-size: 12pt;\"><a href=\"..\/..\/images\/2019\/Determine\/Determina_n_199_dell11-09-2019.pdf\">Determina di approvazione preventivo ed impegno somme, per l&#8217;affidamento della fornitura, nell&#8217;ambito della gara informale, ai sensi dell&#8217;art. 36, comma 2, lettera a), del D.Lgs. n. 50 del 18 aprile 2016 e ss.mm.ii., di gasolio per autotrazione, per l&#8217;azionamneto dei mezzi, per la manutenzione ordinaria, lungo i comprensori irrigui consortili, campagna irrigua 2019, alla ditta Gandolfo s.r.l. CIG: Z8F29A478D.<\/a><\/span><\/p>\n","protected":false},"featured_media":0,"template":"","meta":{"_acf_changed":false,"_lmt_disableupdate":"no","_lmt_disable":""},"categoria_albo_pretorio":[316,318],"class_list":["post-15913","amm_trasparente","type-amm_trasparente","status-publish","hentry","categoria_albo_pretorio-provvedimenti","categoria_albo_pretorio-provvedimenti-dirigenti"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Determina di approvazione preventivo ed impegno somme, per l&#039;affidamento della fornitura, nell&#039;ambito della gara informale, ai sensi dell&#039;art. 36, comma 2, lettera a), del D.Lgs. n. 50 del 18 aprile 2016 e ss.mm.ii., di gasolio per autotrazione, per l&#039;azionamneto dei mezzi, per la manutenzione ordinaria, lungo i comprensori irrigui consortili, campagna irrigua 2019, alla ditta Gandolfo s.r.l. CIG: Z8F29A478D. - Consorzio di Bonifica Palermo 2<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.consorziobonifica.it\/palermo2\/amm_trasparente\/determina-n-199-dell11-09-2019\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Determina di approvazione preventivo ed impegno somme, per l&#039;affidamento della fornitura, nell&#039;ambito della gara informale, ai sensi dell&#039;art. 36, comma 2, lettera a), del D.Lgs. n. 50 del 18 aprile 2016 e ss.mm.ii., di gasolio per autotrazione, per l&#039;azionamneto dei mezzi, per la manutenzione ordinaria, lungo i comprensori irrigui consortili, campagna irrigua 2019, alla ditta Gandolfo s.r.l. CIG: Z8F29A478D. - Consorzio di Bonifica Palermo 2\" \/>\n<meta property=\"og:description\" content=\"Determina di approvazione preventivo ed impegno somme, per l&#8217;affidamento della fornitura, nell&#8217;ambito della gara informale, ai sensi dell&#8217;art. 36, comma 2, lettera a), del D.Lgs. ...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.consorziobonifica.it\/palermo2\/amm_trasparente\/determina-n-199-dell11-09-2019\/\" \/>\n<meta property=\"og:site_name\" content=\"Consorzio di Bonifica Palermo 2\" \/>\n<meta property=\"article:modified_time\" content=\"2020-04-07T12:59:24+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.consorziobonifica.it\\\/palermo2\\\/amm_trasparente\\\/determina-n-199-dell11-09-2019\\\/\",\"url\":\"https:\\\/\\\/www.consorziobonifica.it\\\/palermo2\\\/amm_trasparente\\\/determina-n-199-dell11-09-2019\\\/\",\"name\":\"Determina di approvazione preventivo ed impegno somme, per l'affidamento della fornitura, nell'ambito della gara informale, ai sensi dell'art. 36, comma 2, lettera a), del D.Lgs. n. 50 del 18 aprile 2016 e ss.mm.ii., di gasolio per autotrazione, per l'azionamneto dei mezzi, per la manutenzione ordinaria, lungo i comprensori irrigui consortili, campagna irrigua 2019, alla ditta Gandolfo s.r.l. CIG: Z8F29A478D. - Consorzio di Bonifica Palermo 2\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.consorziobonifica.it\\\/palermo2\\\/#website\"},\"datePublished\":\"2019-10-18T17:19:06+00:00\",\"dateModified\":\"2020-04-07T12:59:24+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.consorziobonifica.it\\\/palermo2\\\/amm_trasparente\\\/determina-n-199-dell11-09-2019\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.consorziobonifica.it\\\/palermo2\\\/amm_trasparente\\\/determina-n-199-dell11-09-2019\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.consorziobonifica.it\\\/palermo2\\\/amm_trasparente\\\/determina-n-199-dell11-09-2019\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.consorziobonifica.it\\\/palermo2\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Determina di approvazione preventivo ed impegno somme, per l&#8217;affidamento della fornitura, nell&#8217;ambito della gara informale, ai sensi dell&#8217;art. 36, comma 2, lettera a), del D.Lgs. n. 50 del 18 aprile 2016 e ss.mm.ii., di gasolio per autotrazione, per l&#8217;azionamneto dei mezzi, per la manutenzione ordinaria, lungo i comprensori irrigui consortili, campagna irrigua 2019, alla ditta Gandolfo s.r.l. CIG: Z8F29A478D.\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.consorziobonifica.it\\\/palermo2\\\/#website\",\"url\":\"https:\\\/\\\/www.consorziobonifica.it\\\/palermo2\\\/\",\"name\":\"Consorzio di Bonifica Palermo 2\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.consorziobonifica.it\\\/palermo2\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.consorziobonifica.it\\\/palermo2\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.consorziobonifica.it\\\/palermo2\\\/#organization\",\"name\":\"Consorzio di bonifica 2 Palermo\",\"url\":\"https:\\\/\\\/www.consorziobonifica.it\\\/palermo2\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.consorziobonifica.it\\\/palermo2\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.consorziobonifica.it\\\/palermo2\\\/wp-content\\\/uploads\\\/2019\\\/11\\\/logo-consorzio.png\",\"contentUrl\":\"https:\\\/\\\/www.consorziobonifica.it\\\/palermo2\\\/wp-content\\\/uploads\\\/2019\\\/11\\\/logo-consorzio.png\",\"width\":350,\"height\":196,\"caption\":\"Consorzio di bonifica 2 Palermo\"},\"image\":{\"@id\":\"https:\\\/\\\/www.consorziobonifica.it\\\/palermo2\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Determina di approvazione preventivo ed impegno somme, per l'affidamento della fornitura, nell'ambito della gara informale, ai sensi dell'art. 36, comma 2, lettera a), del D.Lgs. n. 50 del 18 aprile 2016 e ss.mm.ii., di gasolio per autotrazione, per l'azionamneto dei mezzi, per la manutenzione ordinaria, lungo i comprensori irrigui consortili, campagna irrigua 2019, alla ditta Gandolfo s.r.l. CIG: Z8F29A478D. - Consorzio di Bonifica Palermo 2","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.consorziobonifica.it\/palermo2\/amm_trasparente\/determina-n-199-dell11-09-2019\/","og_locale":"it_IT","og_type":"article","og_title":"Determina di approvazione preventivo ed impegno somme, per l'affidamento della fornitura, nell'ambito della gara informale, ai sensi dell'art. 36, comma 2, lettera a), del D.Lgs. n. 50 del 18 aprile 2016 e ss.mm.ii., di gasolio per autotrazione, per l'azionamneto dei mezzi, per la manutenzione ordinaria, lungo i comprensori irrigui consortili, campagna irrigua 2019, alla ditta Gandolfo s.r.l. CIG: Z8F29A478D. - Consorzio di Bonifica Palermo 2","og_description":"Determina di approvazione preventivo ed impegno somme, per l&#8217;affidamento della fornitura, nell&#8217;ambito della gara informale, ai sensi dell&#8217;art. 36, comma 2, lettera a), del D.Lgs. ...","og_url":"https:\/\/www.consorziobonifica.it\/palermo2\/amm_trasparente\/determina-n-199-dell11-09-2019\/","og_site_name":"Consorzio di Bonifica Palermo 2","article_modified_time":"2020-04-07T12:59:24+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.consorziobonifica.it\/palermo2\/amm_trasparente\/determina-n-199-dell11-09-2019\/","url":"https:\/\/www.consorziobonifica.it\/palermo2\/amm_trasparente\/determina-n-199-dell11-09-2019\/","name":"Determina di approvazione preventivo ed impegno somme, per l'affidamento della fornitura, nell'ambito della gara informale, ai sensi dell'art. 36, comma 2, lettera a), del D.Lgs. n. 50 del 18 aprile 2016 e ss.mm.ii., di gasolio per autotrazione, per l'azionamneto dei mezzi, per la manutenzione ordinaria, lungo i comprensori irrigui consortili, campagna irrigua 2019, alla ditta Gandolfo s.r.l. CIG: Z8F29A478D. - Consorzio di Bonifica Palermo 2","isPartOf":{"@id":"https:\/\/www.consorziobonifica.it\/palermo2\/#website"},"datePublished":"2019-10-18T17:19:06+00:00","dateModified":"2020-04-07T12:59:24+00:00","breadcrumb":{"@id":"https:\/\/www.consorziobonifica.it\/palermo2\/amm_trasparente\/determina-n-199-dell11-09-2019\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.consorziobonifica.it\/palermo2\/amm_trasparente\/determina-n-199-dell11-09-2019\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.consorziobonifica.it\/palermo2\/amm_trasparente\/determina-n-199-dell11-09-2019\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.consorziobonifica.it\/palermo2\/"},{"@type":"ListItem","position":2,"name":"Determina di approvazione preventivo ed impegno somme, per l&#8217;affidamento della fornitura, nell&#8217;ambito della gara informale, ai sensi dell&#8217;art. 36, comma 2, lettera a), del D.Lgs. n. 50 del 18 aprile 2016 e ss.mm.ii., di gasolio per autotrazione, per l&#8217;azionamneto dei mezzi, per la manutenzione ordinaria, lungo i comprensori irrigui consortili, campagna irrigua 2019, alla ditta Gandolfo s.r.l. CIG: Z8F29A478D."}]},{"@type":"WebSite","@id":"https:\/\/www.consorziobonifica.it\/palermo2\/#website","url":"https:\/\/www.consorziobonifica.it\/palermo2\/","name":"Consorzio di Bonifica Palermo 2","description":"","publisher":{"@id":"https:\/\/www.consorziobonifica.it\/palermo2\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.consorziobonifica.it\/palermo2\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.consorziobonifica.it\/palermo2\/#organization","name":"Consorzio di bonifica 2 Palermo","url":"https:\/\/www.consorziobonifica.it\/palermo2\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.consorziobonifica.it\/palermo2\/#\/schema\/logo\/image\/","url":"https:\/\/www.consorziobonifica.it\/palermo2\/wp-content\/uploads\/2019\/11\/logo-consorzio.png","contentUrl":"https:\/\/www.consorziobonifica.it\/palermo2\/wp-content\/uploads\/2019\/11\/logo-consorzio.png","width":350,"height":196,"caption":"Consorzio di bonifica 2 Palermo"},"image":{"@id":"https:\/\/www.consorziobonifica.it\/palermo2\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.consorziobonifica.it\/palermo2\/wp-json\/wp\/v2\/amm_trasparente\/15913","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.consorziobonifica.it\/palermo2\/wp-json\/wp\/v2\/amm_trasparente"}],"about":[{"href":"https:\/\/www.consorziobonifica.it\/palermo2\/wp-json\/wp\/v2\/types\/amm_trasparente"}],"wp:attachment":[{"href":"https:\/\/www.consorziobonifica.it\/palermo2\/wp-json\/wp\/v2\/media?parent=15913"}],"wp:term":[{"taxonomy":"categoria_albo_pretorio","embeddable":true,"href":"https:\/\/www.consorziobonifica.it\/palermo2\/wp-json\/wp\/v2\/categoria_albo_pretorio?post=15913"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}