{"id":16405,"date":"2020-02-28T18:37:55","date_gmt":"2020-02-28T17:37:55","guid":{"rendered":"http:\/\/www.consorziobonifica.it\/palermo2\/amm_trasparente\/determina-n-284-del-29-11-2019"},"modified":"2020-04-02T13:09:35","modified_gmt":"2020-04-02T11:09:35","slug":"determina-n-284-del-29-11-2019","status":"publish","type":"amm_trasparente","link":"https:\/\/www.consorziobonifica.it\/palermo2\/amm_trasparente\/determina-n-284-del-29-11-2019\/","title":{"rendered":"Approvazione preventivo e impegno, a seguito affidamento diretto, ai sensi dell&#8217;art. 36, comma 2, lettera a), del D. Lgs. n. 50 del 18 aprile 2016 e ss.mm.ii., della fornitura di materiale ed attrezzature varie, per gli interventi di manutenzione nei comprensori irrigui, per gli interventi di manutenzione straordinaria delle reti irrigue consortili, alla ditta Mirto s.r.l.. [SMART CIG]: ZD62A6B5AE."},"content":{"rendered":"<p style=\"text-align: justify;\"><span style=\"font-family: 'times new roman', times; font-size: 12pt;\"><a href=\"..\/..\/images\/2019\/Determine\/Determina_n_284_del_29-11-2019.pdf\">Approvazione preventivo e impegno, a seguito affidamento diretto, ai sensi dell&#8217;art. 36, comma 2, lettera a), del D. Lgs. n. 50 del 18 aprile 2016 e ss.mm.ii., della fornitura di materiale ed attrezzature varie, per gli interventi di manutenzione nei comprensori irrigui, per gli interventi di manutenzione straordinaria delle reti irrigue consortili, alla ditta Mirto s.r.l.. [SMART CIG]: ZD62A6B5AE.<\/a><\/span><a href=\"..\/..\/images\/2019\/Determine\/Determina_n_284_del_29-11-2019.pdf\"><br \/>\n<\/a><\/p>\n","protected":false},"featured_media":0,"template":"","meta":{"_acf_changed":false,"_lmt_disableupdate":"no","_lmt_disable":""},"categoria_albo_pretorio":[316,318],"class_list":["post-16405","amm_trasparente","type-amm_trasparente","status-publish","hentry","categoria_albo_pretorio-provvedimenti","categoria_albo_pretorio-provvedimenti-dirigenti"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Approvazione preventivo e impegno, a seguito affidamento diretto, ai sensi dell&#039;art. 36, comma 2, lettera a), del D. Lgs. n. 50 del 18 aprile 2016 e ss.mm.ii., della fornitura di materiale ed attrezzature varie, per gli interventi di manutenzione nei comprensori irrigui, per gli interventi di manutenzione straordinaria delle reti irrigue consortili, alla ditta Mirto s.r.l.. [SMART CIG]: ZD62A6B5AE. - Consorzio di Bonifica Palermo 2<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.consorziobonifica.it\/palermo2\/amm_trasparente\/determina-n-284-del-29-11-2019\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Approvazione preventivo e impegno, a seguito affidamento diretto, ai sensi dell&#039;art. 36, comma 2, lettera a), del D. Lgs. n. 50 del 18 aprile 2016 e ss.mm.ii., della fornitura di materiale ed attrezzature varie, per gli interventi di manutenzione nei comprensori irrigui, per gli interventi di manutenzione straordinaria delle reti irrigue consortili, alla ditta Mirto s.r.l.. [SMART CIG]: ZD62A6B5AE. - Consorzio di Bonifica Palermo 2\" \/>\n<meta property=\"og:description\" content=\"Approvazione preventivo e impegno, a seguito affidamento diretto, ai sensi dell&#8217;art. 36, comma 2, lettera a), del D. Lgs. n. 50 del 18 aprile 2016 ...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.consorziobonifica.it\/palermo2\/amm_trasparente\/determina-n-284-del-29-11-2019\/\" \/>\n<meta property=\"og:site_name\" content=\"Consorzio di Bonifica Palermo 2\" \/>\n<meta property=\"article:modified_time\" content=\"2020-04-02T11:09:35+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.consorziobonifica.it\\\/palermo2\\\/amm_trasparente\\\/determina-n-284-del-29-11-2019\\\/\",\"url\":\"https:\\\/\\\/www.consorziobonifica.it\\\/palermo2\\\/amm_trasparente\\\/determina-n-284-del-29-11-2019\\\/\",\"name\":\"Approvazione preventivo e impegno, a seguito affidamento diretto, ai sensi dell'art. 36, comma 2, lettera a), del D. Lgs. n. 50 del 18 aprile 2016 e ss.mm.ii., della fornitura di materiale ed attrezzature varie, per gli interventi di manutenzione nei comprensori irrigui, per gli interventi di manutenzione straordinaria delle reti irrigue consortili, alla ditta Mirto s.r.l.. [SMART CIG]: ZD62A6B5AE. - Consorzio di Bonifica Palermo 2\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.consorziobonifica.it\\\/palermo2\\\/#website\"},\"datePublished\":\"2020-02-28T17:37:55+00:00\",\"dateModified\":\"2020-04-02T11:09:35+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.consorziobonifica.it\\\/palermo2\\\/amm_trasparente\\\/determina-n-284-del-29-11-2019\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.consorziobonifica.it\\\/palermo2\\\/amm_trasparente\\\/determina-n-284-del-29-11-2019\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.consorziobonifica.it\\\/palermo2\\\/amm_trasparente\\\/determina-n-284-del-29-11-2019\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.consorziobonifica.it\\\/palermo2\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Approvazione preventivo e impegno, a seguito affidamento diretto, ai sensi dell&#8217;art. 36, comma 2, lettera a), del D. Lgs. n. 50 del 18 aprile 2016 e ss.mm.ii., della fornitura di materiale ed attrezzature varie, per gli interventi di manutenzione nei comprensori irrigui, per gli interventi di manutenzione straordinaria delle reti irrigue consortili, alla ditta Mirto s.r.l.. [SMART CIG]: ZD62A6B5AE.\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.consorziobonifica.it\\\/palermo2\\\/#website\",\"url\":\"https:\\\/\\\/www.consorziobonifica.it\\\/palermo2\\\/\",\"name\":\"Consorzio di Bonifica Palermo 2\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.consorziobonifica.it\\\/palermo2\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.consorziobonifica.it\\\/palermo2\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.consorziobonifica.it\\\/palermo2\\\/#organization\",\"name\":\"Consorzio di bonifica 2 Palermo\",\"url\":\"https:\\\/\\\/www.consorziobonifica.it\\\/palermo2\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.consorziobonifica.it\\\/palermo2\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.consorziobonifica.it\\\/palermo2\\\/wp-content\\\/uploads\\\/2019\\\/11\\\/logo-consorzio.png\",\"contentUrl\":\"https:\\\/\\\/www.consorziobonifica.it\\\/palermo2\\\/wp-content\\\/uploads\\\/2019\\\/11\\\/logo-consorzio.png\",\"width\":350,\"height\":196,\"caption\":\"Consorzio di bonifica 2 Palermo\"},\"image\":{\"@id\":\"https:\\\/\\\/www.consorziobonifica.it\\\/palermo2\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Approvazione preventivo e impegno, a seguito affidamento diretto, ai sensi dell'art. 36, comma 2, lettera a), del D. Lgs. n. 50 del 18 aprile 2016 e ss.mm.ii., della fornitura di materiale ed attrezzature varie, per gli interventi di manutenzione nei comprensori irrigui, per gli interventi di manutenzione straordinaria delle reti irrigue consortili, alla ditta Mirto s.r.l.. [SMART CIG]: ZD62A6B5AE. - Consorzio di Bonifica Palermo 2","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.consorziobonifica.it\/palermo2\/amm_trasparente\/determina-n-284-del-29-11-2019\/","og_locale":"it_IT","og_type":"article","og_title":"Approvazione preventivo e impegno, a seguito affidamento diretto, ai sensi dell'art. 36, comma 2, lettera a), del D. Lgs. n. 50 del 18 aprile 2016 e ss.mm.ii., della fornitura di materiale ed attrezzature varie, per gli interventi di manutenzione nei comprensori irrigui, per gli interventi di manutenzione straordinaria delle reti irrigue consortili, alla ditta Mirto s.r.l.. [SMART CIG]: ZD62A6B5AE. - Consorzio di Bonifica Palermo 2","og_description":"Approvazione preventivo e impegno, a seguito affidamento diretto, ai sensi dell&#8217;art. 36, comma 2, lettera a), del D. Lgs. n. 50 del 18 aprile 2016 ...","og_url":"https:\/\/www.consorziobonifica.it\/palermo2\/amm_trasparente\/determina-n-284-del-29-11-2019\/","og_site_name":"Consorzio di Bonifica Palermo 2","article_modified_time":"2020-04-02T11:09:35+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.consorziobonifica.it\/palermo2\/amm_trasparente\/determina-n-284-del-29-11-2019\/","url":"https:\/\/www.consorziobonifica.it\/palermo2\/amm_trasparente\/determina-n-284-del-29-11-2019\/","name":"Approvazione preventivo e impegno, a seguito affidamento diretto, ai sensi dell'art. 36, comma 2, lettera a), del D. Lgs. n. 50 del 18 aprile 2016 e ss.mm.ii., della fornitura di materiale ed attrezzature varie, per gli interventi di manutenzione nei comprensori irrigui, per gli interventi di manutenzione straordinaria delle reti irrigue consortili, alla ditta Mirto s.r.l.. [SMART CIG]: ZD62A6B5AE. - Consorzio di Bonifica Palermo 2","isPartOf":{"@id":"https:\/\/www.consorziobonifica.it\/palermo2\/#website"},"datePublished":"2020-02-28T17:37:55+00:00","dateModified":"2020-04-02T11:09:35+00:00","breadcrumb":{"@id":"https:\/\/www.consorziobonifica.it\/palermo2\/amm_trasparente\/determina-n-284-del-29-11-2019\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.consorziobonifica.it\/palermo2\/amm_trasparente\/determina-n-284-del-29-11-2019\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.consorziobonifica.it\/palermo2\/amm_trasparente\/determina-n-284-del-29-11-2019\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.consorziobonifica.it\/palermo2\/"},{"@type":"ListItem","position":2,"name":"Approvazione preventivo e impegno, a seguito affidamento diretto, ai sensi dell&#8217;art. 36, comma 2, lettera a), del D. Lgs. n. 50 del 18 aprile 2016 e ss.mm.ii., della fornitura di materiale ed attrezzature varie, per gli interventi di manutenzione nei comprensori irrigui, per gli interventi di manutenzione straordinaria delle reti irrigue consortili, alla ditta Mirto s.r.l.. [SMART CIG]: ZD62A6B5AE."}]},{"@type":"WebSite","@id":"https:\/\/www.consorziobonifica.it\/palermo2\/#website","url":"https:\/\/www.consorziobonifica.it\/palermo2\/","name":"Consorzio di Bonifica Palermo 2","description":"","publisher":{"@id":"https:\/\/www.consorziobonifica.it\/palermo2\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.consorziobonifica.it\/palermo2\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.consorziobonifica.it\/palermo2\/#organization","name":"Consorzio di bonifica 2 Palermo","url":"https:\/\/www.consorziobonifica.it\/palermo2\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.consorziobonifica.it\/palermo2\/#\/schema\/logo\/image\/","url":"https:\/\/www.consorziobonifica.it\/palermo2\/wp-content\/uploads\/2019\/11\/logo-consorzio.png","contentUrl":"https:\/\/www.consorziobonifica.it\/palermo2\/wp-content\/uploads\/2019\/11\/logo-consorzio.png","width":350,"height":196,"caption":"Consorzio di bonifica 2 Palermo"},"image":{"@id":"https:\/\/www.consorziobonifica.it\/palermo2\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.consorziobonifica.it\/palermo2\/wp-json\/wp\/v2\/amm_trasparente\/16405","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.consorziobonifica.it\/palermo2\/wp-json\/wp\/v2\/amm_trasparente"}],"about":[{"href":"https:\/\/www.consorziobonifica.it\/palermo2\/wp-json\/wp\/v2\/types\/amm_trasparente"}],"wp:attachment":[{"href":"https:\/\/www.consorziobonifica.it\/palermo2\/wp-json\/wp\/v2\/media?parent=16405"}],"wp:term":[{"taxonomy":"categoria_albo_pretorio","embeddable":true,"href":"https:\/\/www.consorziobonifica.it\/palermo2\/wp-json\/wp\/v2\/categoria_albo_pretorio?post=16405"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}