{"id":16507,"date":"2020-02-28T18:37:58","date_gmt":"2020-02-28T17:37:58","guid":{"rendered":"http:\/\/www.consorziobonifica.it\/palermo2\/amm_trasparente\/determina-n-17-del-03-02-2020"},"modified":"2020-04-01T22:35:38","modified_gmt":"2020-04-01T20:35:38","slug":"determina-n-17-del-03-02-2020","status":"publish","type":"amm_trasparente","link":"https:\/\/www.consorziobonifica.it\/palermo2\/amm_trasparente\/determina-n-17-del-03-02-2020\/","title":{"rendered":"Delibera di Giunta Regionale n. 115 del 20\/05\/2014 &#8211; Consorzi di Bonifica della Sicilia &#8211; Riprogrammazione interventi nel settore delle risorse idriche. Progetto degli &#8220;Interventi di adeguamento alle normative vigenti per la messa in sicurezza delle cabine di trasformazione\u00a0mt\/bt a servizio degli impianti di sollevamento gestiti dal Consorzio di Bonifica 2 Palermo&#8221; &#8211; Importo totale .. 709.543,61 &#8211; Presa d&#8217;atto della rimodulazione quadro economico di progetto a seguito annullamento D.R.S. n. 1651 del 11.10.2019 &#8211; CUP: IT4H17000180002.mt\/bt a servizio degli impianti di sollevamento gestiti dal Consorzio di Bonifica 2 Palermo&#8221; &#8211; Importo totale .. 709.543,61 &#8211; Presa d&#8217;atto della rimodulazione quadro economico di progetto a seguito annullamento D.R.S. n. 1651 del 11.10.2019 &#8211; CUP: IT4H17000180002."},"content":{"rendered":"","protected":false},"featured_media":0,"template":"","meta":{"_acf_changed":false,"_lmt_disableupdate":"no","_lmt_disable":""},"categoria_albo_pretorio":[316,318],"class_list":["post-16507","amm_trasparente","type-amm_trasparente","status-publish","hentry","categoria_albo_pretorio-provvedimenti","categoria_albo_pretorio-provvedimenti-dirigenti"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Delibera di Giunta Regionale n. 115 del 20\/05\/2014 - Consorzi di Bonifica della Sicilia - Riprogrammazione interventi nel settore delle risorse idriche. Progetto degli &quot;Interventi di adeguamento alle normative vigenti per la messa in sicurezza delle cabine di trasformazione\u00a0mt\/bt a servizio degli impianti di sollevamento gestiti dal Consorzio di Bonifica 2 Palermo&quot; - Importo totale .. 709.543,61 - Presa d&#039;atto della rimodulazione quadro economico di progetto a seguito annullamento D.R.S. n. 1651 del 11.10.2019 - CUP: IT4H17000180002.mt\/bt a servizio degli impianti di sollevamento gestiti dal Consorzio di Bonifica 2 Palermo&quot; - Importo totale .. 709.543,61 - Presa d&#039;atto della rimodulazione quadro economico di progetto a seguito annullamento D.R.S. n. 1651 del 11.10.2019 - CUP: IT4H17000180002. - Consorzio di Bonifica Palermo 2<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.consorziobonifica.it\/palermo2\/amm_trasparente\/determina-n-17-del-03-02-2020\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Delibera di Giunta Regionale n. 115 del 20\/05\/2014 - Consorzi di Bonifica della Sicilia - Riprogrammazione interventi nel settore delle risorse idriche. Progetto degli &quot;Interventi di adeguamento alle normative vigenti per la messa in sicurezza delle cabine di trasformazione\u00a0mt\/bt a servizio degli impianti di sollevamento gestiti dal Consorzio di Bonifica 2 Palermo&quot; - Importo totale .. 709.543,61 - Presa d&#039;atto della rimodulazione quadro economico di progetto a seguito annullamento D.R.S. n. 1651 del 11.10.2019 - CUP: IT4H17000180002.mt\/bt a servizio degli impianti di sollevamento gestiti dal Consorzio di Bonifica 2 Palermo&quot; - Importo totale .. 709.543,61 - Presa d&#039;atto della rimodulazione quadro economico di progetto a seguito annullamento D.R.S. n. 1651 del 11.10.2019 - CUP: IT4H17000180002. - Consorzio di Bonifica Palermo 2\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.consorziobonifica.it\/palermo2\/amm_trasparente\/determina-n-17-del-03-02-2020\/\" \/>\n<meta property=\"og:site_name\" content=\"Consorzio di Bonifica Palermo 2\" \/>\n<meta property=\"article:modified_time\" content=\"2020-04-01T20:35:38+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.consorziobonifica.it\\\/palermo2\\\/amm_trasparente\\\/determina-n-17-del-03-02-2020\\\/\",\"url\":\"https:\\\/\\\/www.consorziobonifica.it\\\/palermo2\\\/amm_trasparente\\\/determina-n-17-del-03-02-2020\\\/\",\"name\":\"Delibera di Giunta Regionale n. 115 del 20\\\/05\\\/2014 - Consorzi di Bonifica della Sicilia - Riprogrammazione interventi nel settore delle risorse idriche. Progetto degli \\\"Interventi di adeguamento alle normative vigenti per la messa in sicurezza delle cabine di trasformazione\u00a0mt\\\/bt a servizio degli impianti di sollevamento gestiti dal Consorzio di Bonifica 2 Palermo\\\" - Importo totale .. 709.543,61 - Presa d'atto della rimodulazione quadro economico di progetto a seguito annullamento D.R.S. n. 1651 del 11.10.2019 - CUP: IT4H17000180002.mt\\\/bt a servizio degli impianti di sollevamento gestiti dal Consorzio di Bonifica 2 Palermo\\\" - Importo totale .. 709.543,61 - Presa d'atto della rimodulazione quadro economico di progetto a seguito annullamento D.R.S. n. 1651 del 11.10.2019 - CUP: IT4H17000180002. - Consorzio di Bonifica Palermo 2\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.consorziobonifica.it\\\/palermo2\\\/#website\"},\"datePublished\":\"2020-02-28T17:37:58+00:00\",\"dateModified\":\"2020-04-01T20:35:38+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.consorziobonifica.it\\\/palermo2\\\/amm_trasparente\\\/determina-n-17-del-03-02-2020\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.consorziobonifica.it\\\/palermo2\\\/amm_trasparente\\\/determina-n-17-del-03-02-2020\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.consorziobonifica.it\\\/palermo2\\\/amm_trasparente\\\/determina-n-17-del-03-02-2020\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.consorziobonifica.it\\\/palermo2\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Delibera di Giunta Regionale n. 115 del 20\\\/05\\\/2014 &#8211; Consorzi di Bonifica della Sicilia &#8211; Riprogrammazione interventi nel settore delle risorse idriche. Progetto degli &#8220;Interventi di adeguamento alle normative vigenti per la messa in sicurezza delle cabine di trasformazione\u00a0mt\\\/bt a servizio degli impianti di sollevamento gestiti dal Consorzio di Bonifica 2 Palermo&#8221; &#8211; Importo totale .. 709.543,61 &#8211; Presa d&#8217;atto della rimodulazione quadro economico di progetto a seguito annullamento D.R.S. n. 1651 del 11.10.2019 &#8211; CUP: IT4H17000180002.mt\\\/bt a servizio degli impianti di sollevamento gestiti dal Consorzio di Bonifica 2 Palermo&#8221; &#8211; Importo totale .. 709.543,61 &#8211; Presa d&#8217;atto della rimodulazione quadro economico di progetto a seguito annullamento D.R.S. n. 1651 del 11.10.2019 &#8211; CUP: IT4H17000180002.\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.consorziobonifica.it\\\/palermo2\\\/#website\",\"url\":\"https:\\\/\\\/www.consorziobonifica.it\\\/palermo2\\\/\",\"name\":\"Consorzio di Bonifica Palermo 2\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.consorziobonifica.it\\\/palermo2\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.consorziobonifica.it\\\/palermo2\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.consorziobonifica.it\\\/palermo2\\\/#organization\",\"name\":\"Consorzio di bonifica 2 Palermo\",\"url\":\"https:\\\/\\\/www.consorziobonifica.it\\\/palermo2\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.consorziobonifica.it\\\/palermo2\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.consorziobonifica.it\\\/palermo2\\\/wp-content\\\/uploads\\\/2019\\\/11\\\/logo-consorzio.png\",\"contentUrl\":\"https:\\\/\\\/www.consorziobonifica.it\\\/palermo2\\\/wp-content\\\/uploads\\\/2019\\\/11\\\/logo-consorzio.png\",\"width\":350,\"height\":196,\"caption\":\"Consorzio di bonifica 2 Palermo\"},\"image\":{\"@id\":\"https:\\\/\\\/www.consorziobonifica.it\\\/palermo2\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Delibera di Giunta Regionale n. 115 del 20\/05\/2014 - Consorzi di Bonifica della Sicilia - Riprogrammazione interventi nel settore delle risorse idriche. Progetto degli \"Interventi di adeguamento alle normative vigenti per la messa in sicurezza delle cabine di trasformazione\u00a0mt\/bt a servizio degli impianti di sollevamento gestiti dal Consorzio di Bonifica 2 Palermo\" - Importo totale .. 709.543,61 - Presa d'atto della rimodulazione quadro economico di progetto a seguito annullamento D.R.S. n. 1651 del 11.10.2019 - CUP: IT4H17000180002.mt\/bt a servizio degli impianti di sollevamento gestiti dal Consorzio di Bonifica 2 Palermo\" - Importo totale .. 709.543,61 - Presa d'atto della rimodulazione quadro economico di progetto a seguito annullamento D.R.S. n. 1651 del 11.10.2019 - CUP: IT4H17000180002. - Consorzio di Bonifica Palermo 2","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.consorziobonifica.it\/palermo2\/amm_trasparente\/determina-n-17-del-03-02-2020\/","og_locale":"it_IT","og_type":"article","og_title":"Delibera di Giunta Regionale n. 115 del 20\/05\/2014 - Consorzi di Bonifica della Sicilia - Riprogrammazione interventi nel settore delle risorse idriche. Progetto degli \"Interventi di adeguamento alle normative vigenti per la messa in sicurezza delle cabine di trasformazione\u00a0mt\/bt a servizio degli impianti di sollevamento gestiti dal Consorzio di Bonifica 2 Palermo\" - Importo totale .. 709.543,61 - Presa d'atto della rimodulazione quadro economico di progetto a seguito annullamento D.R.S. n. 1651 del 11.10.2019 - CUP: IT4H17000180002.mt\/bt a servizio degli impianti di sollevamento gestiti dal Consorzio di Bonifica 2 Palermo\" - Importo totale .. 709.543,61 - Presa d'atto della rimodulazione quadro economico di progetto a seguito annullamento D.R.S. n. 1651 del 11.10.2019 - CUP: IT4H17000180002. - Consorzio di Bonifica Palermo 2","og_url":"https:\/\/www.consorziobonifica.it\/palermo2\/amm_trasparente\/determina-n-17-del-03-02-2020\/","og_site_name":"Consorzio di Bonifica Palermo 2","article_modified_time":"2020-04-01T20:35:38+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.consorziobonifica.it\/palermo2\/amm_trasparente\/determina-n-17-del-03-02-2020\/","url":"https:\/\/www.consorziobonifica.it\/palermo2\/amm_trasparente\/determina-n-17-del-03-02-2020\/","name":"Delibera di Giunta Regionale n. 115 del 20\/05\/2014 - Consorzi di Bonifica della Sicilia - Riprogrammazione interventi nel settore delle risorse idriche. Progetto degli \"Interventi di adeguamento alle normative vigenti per la messa in sicurezza delle cabine di trasformazione\u00a0mt\/bt a servizio degli impianti di sollevamento gestiti dal Consorzio di Bonifica 2 Palermo\" - Importo totale .. 709.543,61 - Presa d'atto della rimodulazione quadro economico di progetto a seguito annullamento D.R.S. n. 1651 del 11.10.2019 - CUP: IT4H17000180002.mt\/bt a servizio degli impianti di sollevamento gestiti dal Consorzio di Bonifica 2 Palermo\" - Importo totale .. 709.543,61 - Presa d'atto della rimodulazione quadro economico di progetto a seguito annullamento D.R.S. n. 1651 del 11.10.2019 - CUP: IT4H17000180002. - Consorzio di Bonifica Palermo 2","isPartOf":{"@id":"https:\/\/www.consorziobonifica.it\/palermo2\/#website"},"datePublished":"2020-02-28T17:37:58+00:00","dateModified":"2020-04-01T20:35:38+00:00","breadcrumb":{"@id":"https:\/\/www.consorziobonifica.it\/palermo2\/amm_trasparente\/determina-n-17-del-03-02-2020\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.consorziobonifica.it\/palermo2\/amm_trasparente\/determina-n-17-del-03-02-2020\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.consorziobonifica.it\/palermo2\/amm_trasparente\/determina-n-17-del-03-02-2020\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.consorziobonifica.it\/palermo2\/"},{"@type":"ListItem","position":2,"name":"Delibera di Giunta Regionale n. 115 del 20\/05\/2014 &#8211; Consorzi di Bonifica della Sicilia &#8211; Riprogrammazione interventi nel settore delle risorse idriche. Progetto degli &#8220;Interventi di adeguamento alle normative vigenti per la messa in sicurezza delle cabine di trasformazione\u00a0mt\/bt a servizio degli impianti di sollevamento gestiti dal Consorzio di Bonifica 2 Palermo&#8221; &#8211; Importo totale .. 709.543,61 &#8211; Presa d&#8217;atto della rimodulazione quadro economico di progetto a seguito annullamento D.R.S. n. 1651 del 11.10.2019 &#8211; CUP: IT4H17000180002.mt\/bt a servizio degli impianti di sollevamento gestiti dal Consorzio di Bonifica 2 Palermo&#8221; &#8211; Importo totale .. 709.543,61 &#8211; Presa d&#8217;atto della rimodulazione quadro economico di progetto a seguito annullamento D.R.S. n. 1651 del 11.10.2019 &#8211; CUP: IT4H17000180002."}]},{"@type":"WebSite","@id":"https:\/\/www.consorziobonifica.it\/palermo2\/#website","url":"https:\/\/www.consorziobonifica.it\/palermo2\/","name":"Consorzio di Bonifica Palermo 2","description":"","publisher":{"@id":"https:\/\/www.consorziobonifica.it\/palermo2\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.consorziobonifica.it\/palermo2\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.consorziobonifica.it\/palermo2\/#organization","name":"Consorzio di bonifica 2 Palermo","url":"https:\/\/www.consorziobonifica.it\/palermo2\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.consorziobonifica.it\/palermo2\/#\/schema\/logo\/image\/","url":"https:\/\/www.consorziobonifica.it\/palermo2\/wp-content\/uploads\/2019\/11\/logo-consorzio.png","contentUrl":"https:\/\/www.consorziobonifica.it\/palermo2\/wp-content\/uploads\/2019\/11\/logo-consorzio.png","width":350,"height":196,"caption":"Consorzio di bonifica 2 Palermo"},"image":{"@id":"https:\/\/www.consorziobonifica.it\/palermo2\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.consorziobonifica.it\/palermo2\/wp-json\/wp\/v2\/amm_trasparente\/16507","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.consorziobonifica.it\/palermo2\/wp-json\/wp\/v2\/amm_trasparente"}],"about":[{"href":"https:\/\/www.consorziobonifica.it\/palermo2\/wp-json\/wp\/v2\/types\/amm_trasparente"}],"wp:attachment":[{"href":"https:\/\/www.consorziobonifica.it\/palermo2\/wp-json\/wp\/v2\/media?parent=16507"}],"wp:term":[{"taxonomy":"categoria_albo_pretorio","embeddable":true,"href":"https:\/\/www.consorziobonifica.it\/palermo2\/wp-json\/wp\/v2\/categoria_albo_pretorio?post=16507"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}