{"id":16691,"date":"2020-04-08T09:51:56","date_gmt":"2020-04-08T07:51:56","guid":{"rendered":"http:\/\/www.consorziobonifica.it\/palermo2\/?post_type=amm_trasparente&#038;p=16691"},"modified":"2020-04-08T10:01:24","modified_gmt":"2020-04-08T08:01:24","slug":"pagamento-a-seguito-affidamento-diretto-ai-sensi-dellart-36-comma-2-lettera-a-del-d-lgs-n-50-del-18-aprile-2016-e-ss-mm-ii-della-fornitura-di-giunti-e-collari-di-riparazione-relativi-ag","status":"publish","type":"amm_trasparente","link":"https:\/\/www.consorziobonifica.it\/palermo2\/amm_trasparente\/pagamento-a-seguito-affidamento-diretto-ai-sensi-dellart-36-comma-2-lettera-a-del-d-lgs-n-50-del-18-aprile-2016-e-ss-mm-ii-della-fornitura-di-giunti-e-collari-di-riparazione-relativi-ag\/","title":{"rendered":"Pagamento, a seguito affidamento diretto, ai sensi dell&#8217;art. 36, comma 2, lettera a), del D. Lgs. n. 50 del 18 aprile 2016 e ss.mm.ii., della fornitura di giunti e collari di riparazione, relativi agli interventi di manutenzione delle condotte consortili, ricadenti nel sito COD. SI_PA_00971 COMUNI DI CASTELDACCIA E BAGHERIA, alla ditta Nova Siria S.r.l.. [SMART CIG]: ZE82A9A6A1 CUP: I55D19000090001."},"content":{"rendered":"","protected":false},"featured_media":0,"template":"","meta":{"_acf_changed":false,"_lmt_disableupdate":"no","_lmt_disable":""},"categoria_albo_pretorio":[318],"class_list":["post-16691","amm_trasparente","type-amm_trasparente","status-publish","hentry","categoria_albo_pretorio-provvedimenti-dirigenti"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Pagamento, a seguito affidamento diretto, ai sensi dell&#039;art. 36, comma 2, lettera a), del D. Lgs. n. 50 del 18 aprile 2016 e ss.mm.ii., della fornitura di giunti e collari di riparazione, relativi agli interventi di manutenzione delle condotte consortili, ricadenti nel sito COD. SI_PA_00971 COMUNI DI CASTELDACCIA E BAGHERIA, alla ditta Nova Siria S.r.l.. [SMART CIG]: ZE82A9A6A1 CUP: I55D19000090001. - Consorzio di Bonifica Palermo 2<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.consorziobonifica.it\/palermo2\/amm_trasparente\/pagamento-a-seguito-affidamento-diretto-ai-sensi-dellart-36-comma-2-lettera-a-del-d-lgs-n-50-del-18-aprile-2016-e-ss-mm-ii-della-fornitura-di-giunti-e-collari-di-riparazione-relativi-ag\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Pagamento, a seguito affidamento diretto, ai sensi dell&#039;art. 36, comma 2, lettera a), del D. Lgs. n. 50 del 18 aprile 2016 e ss.mm.ii., della fornitura di giunti e collari di riparazione, relativi agli interventi di manutenzione delle condotte consortili, ricadenti nel sito COD. SI_PA_00971 COMUNI DI CASTELDACCIA E BAGHERIA, alla ditta Nova Siria S.r.l.. [SMART CIG]: ZE82A9A6A1 CUP: I55D19000090001. - Consorzio di Bonifica Palermo 2\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.consorziobonifica.it\/palermo2\/amm_trasparente\/pagamento-a-seguito-affidamento-diretto-ai-sensi-dellart-36-comma-2-lettera-a-del-d-lgs-n-50-del-18-aprile-2016-e-ss-mm-ii-della-fornitura-di-giunti-e-collari-di-riparazione-relativi-ag\/\" \/>\n<meta property=\"og:site_name\" content=\"Consorzio di Bonifica Palermo 2\" \/>\n<meta property=\"article:modified_time\" content=\"2020-04-08T08:01:24+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.consorziobonifica.it\\\/palermo2\\\/amm_trasparente\\\/pagamento-a-seguito-affidamento-diretto-ai-sensi-dellart-36-comma-2-lettera-a-del-d-lgs-n-50-del-18-aprile-2016-e-ss-mm-ii-della-fornitura-di-giunti-e-collari-di-riparazione-relativi-ag\\\/\",\"url\":\"https:\\\/\\\/www.consorziobonifica.it\\\/palermo2\\\/amm_trasparente\\\/pagamento-a-seguito-affidamento-diretto-ai-sensi-dellart-36-comma-2-lettera-a-del-d-lgs-n-50-del-18-aprile-2016-e-ss-mm-ii-della-fornitura-di-giunti-e-collari-di-riparazione-relativi-ag\\\/\",\"name\":\"Pagamento, a seguito affidamento diretto, ai sensi dell'art. 36, comma 2, lettera a), del D. Lgs. n. 50 del 18 aprile 2016 e ss.mm.ii., della fornitura di giunti e collari di riparazione, relativi agli interventi di manutenzione delle condotte consortili, ricadenti nel sito COD. SI_PA_00971 COMUNI DI CASTELDACCIA E BAGHERIA, alla ditta Nova Siria S.r.l.. [SMART CIG]: ZE82A9A6A1 CUP: I55D19000090001. - Consorzio di Bonifica Palermo 2\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.consorziobonifica.it\\\/palermo2\\\/#website\"},\"datePublished\":\"2020-04-08T07:51:56+00:00\",\"dateModified\":\"2020-04-08T08:01:24+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.consorziobonifica.it\\\/palermo2\\\/amm_trasparente\\\/pagamento-a-seguito-affidamento-diretto-ai-sensi-dellart-36-comma-2-lettera-a-del-d-lgs-n-50-del-18-aprile-2016-e-ss-mm-ii-della-fornitura-di-giunti-e-collari-di-riparazione-relativi-ag\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.consorziobonifica.it\\\/palermo2\\\/amm_trasparente\\\/pagamento-a-seguito-affidamento-diretto-ai-sensi-dellart-36-comma-2-lettera-a-del-d-lgs-n-50-del-18-aprile-2016-e-ss-mm-ii-della-fornitura-di-giunti-e-collari-di-riparazione-relativi-ag\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.consorziobonifica.it\\\/palermo2\\\/amm_trasparente\\\/pagamento-a-seguito-affidamento-diretto-ai-sensi-dellart-36-comma-2-lettera-a-del-d-lgs-n-50-del-18-aprile-2016-e-ss-mm-ii-della-fornitura-di-giunti-e-collari-di-riparazione-relativi-ag\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.consorziobonifica.it\\\/palermo2\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Pagamento, a seguito affidamento diretto, ai sensi dell&#8217;art. 36, comma 2, lettera a), del D. Lgs. n. 50 del 18 aprile 2016 e ss.mm.ii., della fornitura di giunti e collari di riparazione, relativi agli interventi di manutenzione delle condotte consortili, ricadenti nel sito COD. SI_PA_00971 COMUNI DI CASTELDACCIA E BAGHERIA, alla ditta Nova Siria S.r.l.. [SMART CIG]: ZE82A9A6A1 CUP: I55D19000090001.\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.consorziobonifica.it\\\/palermo2\\\/#website\",\"url\":\"https:\\\/\\\/www.consorziobonifica.it\\\/palermo2\\\/\",\"name\":\"Consorzio di Bonifica Palermo 2\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.consorziobonifica.it\\\/palermo2\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.consorziobonifica.it\\\/palermo2\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.consorziobonifica.it\\\/palermo2\\\/#organization\",\"name\":\"Consorzio di bonifica 2 Palermo\",\"url\":\"https:\\\/\\\/www.consorziobonifica.it\\\/palermo2\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.consorziobonifica.it\\\/palermo2\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.consorziobonifica.it\\\/palermo2\\\/wp-content\\\/uploads\\\/2019\\\/11\\\/logo-consorzio.png\",\"contentUrl\":\"https:\\\/\\\/www.consorziobonifica.it\\\/palermo2\\\/wp-content\\\/uploads\\\/2019\\\/11\\\/logo-consorzio.png\",\"width\":350,\"height\":196,\"caption\":\"Consorzio di bonifica 2 Palermo\"},\"image\":{\"@id\":\"https:\\\/\\\/www.consorziobonifica.it\\\/palermo2\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Pagamento, a seguito affidamento diretto, ai sensi dell'art. 36, comma 2, lettera a), del D. Lgs. n. 50 del 18 aprile 2016 e ss.mm.ii., della fornitura di giunti e collari di riparazione, relativi agli interventi di manutenzione delle condotte consortili, ricadenti nel sito COD. SI_PA_00971 COMUNI DI CASTELDACCIA E BAGHERIA, alla ditta Nova Siria S.r.l.. [SMART CIG]: ZE82A9A6A1 CUP: I55D19000090001. - Consorzio di Bonifica Palermo 2","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.consorziobonifica.it\/palermo2\/amm_trasparente\/pagamento-a-seguito-affidamento-diretto-ai-sensi-dellart-36-comma-2-lettera-a-del-d-lgs-n-50-del-18-aprile-2016-e-ss-mm-ii-della-fornitura-di-giunti-e-collari-di-riparazione-relativi-ag\/","og_locale":"it_IT","og_type":"article","og_title":"Pagamento, a seguito affidamento diretto, ai sensi dell'art. 36, comma 2, lettera a), del D. Lgs. n. 50 del 18 aprile 2016 e ss.mm.ii., della fornitura di giunti e collari di riparazione, relativi agli interventi di manutenzione delle condotte consortili, ricadenti nel sito COD. SI_PA_00971 COMUNI DI CASTELDACCIA E BAGHERIA, alla ditta Nova Siria S.r.l.. [SMART CIG]: ZE82A9A6A1 CUP: I55D19000090001. - Consorzio di Bonifica Palermo 2","og_url":"https:\/\/www.consorziobonifica.it\/palermo2\/amm_trasparente\/pagamento-a-seguito-affidamento-diretto-ai-sensi-dellart-36-comma-2-lettera-a-del-d-lgs-n-50-del-18-aprile-2016-e-ss-mm-ii-della-fornitura-di-giunti-e-collari-di-riparazione-relativi-ag\/","og_site_name":"Consorzio di Bonifica Palermo 2","article_modified_time":"2020-04-08T08:01:24+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.consorziobonifica.it\/palermo2\/amm_trasparente\/pagamento-a-seguito-affidamento-diretto-ai-sensi-dellart-36-comma-2-lettera-a-del-d-lgs-n-50-del-18-aprile-2016-e-ss-mm-ii-della-fornitura-di-giunti-e-collari-di-riparazione-relativi-ag\/","url":"https:\/\/www.consorziobonifica.it\/palermo2\/amm_trasparente\/pagamento-a-seguito-affidamento-diretto-ai-sensi-dellart-36-comma-2-lettera-a-del-d-lgs-n-50-del-18-aprile-2016-e-ss-mm-ii-della-fornitura-di-giunti-e-collari-di-riparazione-relativi-ag\/","name":"Pagamento, a seguito affidamento diretto, ai sensi dell'art. 36, comma 2, lettera a), del D. Lgs. n. 50 del 18 aprile 2016 e ss.mm.ii., della fornitura di giunti e collari di riparazione, relativi agli interventi di manutenzione delle condotte consortili, ricadenti nel sito COD. SI_PA_00971 COMUNI DI CASTELDACCIA E BAGHERIA, alla ditta Nova Siria S.r.l.. [SMART CIG]: ZE82A9A6A1 CUP: I55D19000090001. - Consorzio di Bonifica Palermo 2","isPartOf":{"@id":"https:\/\/www.consorziobonifica.it\/palermo2\/#website"},"datePublished":"2020-04-08T07:51:56+00:00","dateModified":"2020-04-08T08:01:24+00:00","breadcrumb":{"@id":"https:\/\/www.consorziobonifica.it\/palermo2\/amm_trasparente\/pagamento-a-seguito-affidamento-diretto-ai-sensi-dellart-36-comma-2-lettera-a-del-d-lgs-n-50-del-18-aprile-2016-e-ss-mm-ii-della-fornitura-di-giunti-e-collari-di-riparazione-relativi-ag\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.consorziobonifica.it\/palermo2\/amm_trasparente\/pagamento-a-seguito-affidamento-diretto-ai-sensi-dellart-36-comma-2-lettera-a-del-d-lgs-n-50-del-18-aprile-2016-e-ss-mm-ii-della-fornitura-di-giunti-e-collari-di-riparazione-relativi-ag\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.consorziobonifica.it\/palermo2\/amm_trasparente\/pagamento-a-seguito-affidamento-diretto-ai-sensi-dellart-36-comma-2-lettera-a-del-d-lgs-n-50-del-18-aprile-2016-e-ss-mm-ii-della-fornitura-di-giunti-e-collari-di-riparazione-relativi-ag\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.consorziobonifica.it\/palermo2\/"},{"@type":"ListItem","position":2,"name":"Pagamento, a seguito affidamento diretto, ai sensi dell&#8217;art. 36, comma 2, lettera a), del D. Lgs. n. 50 del 18 aprile 2016 e ss.mm.ii., della fornitura di giunti e collari di riparazione, relativi agli interventi di manutenzione delle condotte consortili, ricadenti nel sito COD. SI_PA_00971 COMUNI DI CASTELDACCIA E BAGHERIA, alla ditta Nova Siria S.r.l.. [SMART CIG]: ZE82A9A6A1 CUP: I55D19000090001."}]},{"@type":"WebSite","@id":"https:\/\/www.consorziobonifica.it\/palermo2\/#website","url":"https:\/\/www.consorziobonifica.it\/palermo2\/","name":"Consorzio di Bonifica Palermo 2","description":"","publisher":{"@id":"https:\/\/www.consorziobonifica.it\/palermo2\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.consorziobonifica.it\/palermo2\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.consorziobonifica.it\/palermo2\/#organization","name":"Consorzio di bonifica 2 Palermo","url":"https:\/\/www.consorziobonifica.it\/palermo2\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.consorziobonifica.it\/palermo2\/#\/schema\/logo\/image\/","url":"https:\/\/www.consorziobonifica.it\/palermo2\/wp-content\/uploads\/2019\/11\/logo-consorzio.png","contentUrl":"https:\/\/www.consorziobonifica.it\/palermo2\/wp-content\/uploads\/2019\/11\/logo-consorzio.png","width":350,"height":196,"caption":"Consorzio di bonifica 2 Palermo"},"image":{"@id":"https:\/\/www.consorziobonifica.it\/palermo2\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.consorziobonifica.it\/palermo2\/wp-json\/wp\/v2\/amm_trasparente\/16691","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.consorziobonifica.it\/palermo2\/wp-json\/wp\/v2\/amm_trasparente"}],"about":[{"href":"https:\/\/www.consorziobonifica.it\/palermo2\/wp-json\/wp\/v2\/types\/amm_trasparente"}],"wp:attachment":[{"href":"https:\/\/www.consorziobonifica.it\/palermo2\/wp-json\/wp\/v2\/media?parent=16691"}],"wp:term":[{"taxonomy":"categoria_albo_pretorio","embeddable":true,"href":"https:\/\/www.consorziobonifica.it\/palermo2\/wp-json\/wp\/v2\/categoria_albo_pretorio?post=16691"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}