{"id":16946,"date":"2020-06-10T14:53:08","date_gmt":"2020-06-10T12:53:08","guid":{"rendered":"http:\/\/www.consorziobonifica.it\/palermo2\/?post_type=amm_trasparente&#038;p=16946"},"modified":"2020-06-10T14:53:09","modified_gmt":"2020-06-10T12:53:09","slug":"ocdpc-558-2018-primi-interventi-urgenti-di-protezione-civile-in-conseguenza-degli-eccezionale-eventi-meteorologici-che-hanno-interessato-le-regioni-calabria-emilia-romagna-friuli-lazio-lombardia-3","status":"publish","type":"amm_trasparente","link":"https:\/\/www.consorziobonifica.it\/palermo2\/amm_trasparente\/ocdpc-558-2018-primi-interventi-urgenti-di-protezione-civile-in-conseguenza-degli-eccezionale-eventi-meteorologici-che-hanno-interessato-le-regioni-calabria-emilia-romagna-friuli-lazio-lombardia-3\/","title":{"rendered":"OCDPC 558\/2018 &#8220;primi interventi urgenti di protezione civile in conseguenza degli eccezionale eventi meteorologici che hanno interessato le regioni Calabria, Emilia Romagna, Friuli, Lazio, Lombardia Toscana, Sardegna, Sicilia, Veneto e delle Provincie autonome di Trento e Bolzano colpite dagli eccezionali eventi metereologici verificatisi a partire dal mese di ottobre 2018&#8221;. Pagamento, a seguito affidamento diretto, ai sensi dell&#8217;art. 36, comma 2, lettera a) del D.Lgs. 50 del 18 aprile 2016 e ss.mm.ii., della fonitura di valvole a farfalla, per le camere di manovra, ubicate negli impianti consortili, di cui al COD. SI_PA_00975 (COMUNE DI MISILMERI), alla ditta Idroconnect di Fabio Campagna. [SMART CIG]: Z6329F14F7 &#8211; CUP: I65D19000050001."},"content":{"rendered":"","protected":false},"featured_media":0,"template":"","meta":{"_acf_changed":false,"_lmt_disableupdate":"","_lmt_disable":""},"categoria_albo_pretorio":[318],"class_list":["post-16946","amm_trasparente","type-amm_trasparente","status-publish","hentry","categoria_albo_pretorio-provvedimenti-dirigenti"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>OCDPC 558\/2018 &quot;primi interventi urgenti di protezione civile in conseguenza degli eccezionale eventi meteorologici che hanno interessato le regioni Calabria, Emilia Romagna, Friuli, Lazio, Lombardia Toscana, Sardegna, Sicilia, Veneto e delle Provincie autonome di Trento e Bolzano colpite dagli eccezionali eventi metereologici verificatisi a partire dal mese di ottobre 2018&quot;. Pagamento, a seguito affidamento diretto, ai sensi dell&#039;art. 36, comma 2, lettera a) del D.Lgs. 50 del 18 aprile 2016 e ss.mm.ii., della fonitura di valvole a farfalla, per le camere di manovra, ubicate negli impianti consortili, di cui al COD. SI_PA_00975 (COMUNE DI MISILMERI), alla ditta Idroconnect di Fabio Campagna. [SMART CIG]: Z6329F14F7 - CUP: I65D19000050001. - Consorzio di Bonifica Palermo 2<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.consorziobonifica.it\/palermo2\/amm_trasparente\/ocdpc-558-2018-primi-interventi-urgenti-di-protezione-civile-in-conseguenza-degli-eccezionale-eventi-meteorologici-che-hanno-interessato-le-regioni-calabria-emilia-romagna-friuli-lazio-lombardia-3\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"OCDPC 558\/2018 &quot;primi interventi urgenti di protezione civile in conseguenza degli eccezionale eventi meteorologici che hanno interessato le regioni Calabria, Emilia Romagna, Friuli, Lazio, Lombardia Toscana, Sardegna, Sicilia, Veneto e delle Provincie autonome di Trento e Bolzano colpite dagli eccezionali eventi metereologici verificatisi a partire dal mese di ottobre 2018&quot;. Pagamento, a seguito affidamento diretto, ai sensi dell&#039;art. 36, comma 2, lettera a) del D.Lgs. 50 del 18 aprile 2016 e ss.mm.ii., della fonitura di valvole a farfalla, per le camere di manovra, ubicate negli impianti consortili, di cui al COD. SI_PA_00975 (COMUNE DI MISILMERI), alla ditta Idroconnect di Fabio Campagna. [SMART CIG]: Z6329F14F7 - CUP: I65D19000050001. - Consorzio di Bonifica Palermo 2\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.consorziobonifica.it\/palermo2\/amm_trasparente\/ocdpc-558-2018-primi-interventi-urgenti-di-protezione-civile-in-conseguenza-degli-eccezionale-eventi-meteorologici-che-hanno-interessato-le-regioni-calabria-emilia-romagna-friuli-lazio-lombardia-3\/\" \/>\n<meta property=\"og:site_name\" content=\"Consorzio di Bonifica Palermo 2\" \/>\n<meta property=\"article:modified_time\" content=\"2020-06-10T12:53:09+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.consorziobonifica.it\\\/palermo2\\\/amm_trasparente\\\/ocdpc-558-2018-primi-interventi-urgenti-di-protezione-civile-in-conseguenza-degli-eccezionale-eventi-meteorologici-che-hanno-interessato-le-regioni-calabria-emilia-romagna-friuli-lazio-lombardia-3\\\/\",\"url\":\"https:\\\/\\\/www.consorziobonifica.it\\\/palermo2\\\/amm_trasparente\\\/ocdpc-558-2018-primi-interventi-urgenti-di-protezione-civile-in-conseguenza-degli-eccezionale-eventi-meteorologici-che-hanno-interessato-le-regioni-calabria-emilia-romagna-friuli-lazio-lombardia-3\\\/\",\"name\":\"OCDPC 558\\\/2018 \\\"primi interventi urgenti di protezione civile in conseguenza degli eccezionale eventi meteorologici che hanno interessato le regioni Calabria, Emilia Romagna, Friuli, Lazio, Lombardia Toscana, Sardegna, Sicilia, Veneto e delle Provincie autonome di Trento e Bolzano colpite dagli eccezionali eventi metereologici verificatisi a partire dal mese di ottobre 2018\\\". Pagamento, a seguito affidamento diretto, ai sensi dell'art. 36, comma 2, lettera a) del D.Lgs. 50 del 18 aprile 2016 e ss.mm.ii., della fonitura di valvole a farfalla, per le camere di manovra, ubicate negli impianti consortili, di cui al COD. SI_PA_00975 (COMUNE DI MISILMERI), alla ditta Idroconnect di Fabio Campagna. [SMART CIG]: Z6329F14F7 - CUP: I65D19000050001. - Consorzio di Bonifica Palermo 2\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.consorziobonifica.it\\\/palermo2\\\/#website\"},\"datePublished\":\"2020-06-10T12:53:08+00:00\",\"dateModified\":\"2020-06-10T12:53:09+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.consorziobonifica.it\\\/palermo2\\\/amm_trasparente\\\/ocdpc-558-2018-primi-interventi-urgenti-di-protezione-civile-in-conseguenza-degli-eccezionale-eventi-meteorologici-che-hanno-interessato-le-regioni-calabria-emilia-romagna-friuli-lazio-lombardia-3\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.consorziobonifica.it\\\/palermo2\\\/amm_trasparente\\\/ocdpc-558-2018-primi-interventi-urgenti-di-protezione-civile-in-conseguenza-degli-eccezionale-eventi-meteorologici-che-hanno-interessato-le-regioni-calabria-emilia-romagna-friuli-lazio-lombardia-3\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.consorziobonifica.it\\\/palermo2\\\/amm_trasparente\\\/ocdpc-558-2018-primi-interventi-urgenti-di-protezione-civile-in-conseguenza-degli-eccezionale-eventi-meteorologici-che-hanno-interessato-le-regioni-calabria-emilia-romagna-friuli-lazio-lombardia-3\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.consorziobonifica.it\\\/palermo2\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"OCDPC 558\\\/2018 &#8220;primi interventi urgenti di protezione civile in conseguenza degli eccezionale eventi meteorologici che hanno interessato le regioni Calabria, Emilia Romagna, Friuli, Lazio, Lombardia Toscana, Sardegna, Sicilia, Veneto e delle Provincie autonome di Trento e Bolzano colpite dagli eccezionali eventi metereologici verificatisi a partire dal mese di ottobre 2018&#8221;. Pagamento, a seguito affidamento diretto, ai sensi dell&#8217;art. 36, comma 2, lettera a) del D.Lgs. 50 del 18 aprile 2016 e ss.mm.ii., della fonitura di valvole a farfalla, per le camere di manovra, ubicate negli impianti consortili, di cui al COD. SI_PA_00975 (COMUNE DI MISILMERI), alla ditta Idroconnect di Fabio Campagna. [SMART CIG]: Z6329F14F7 &#8211; CUP: I65D19000050001.\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.consorziobonifica.it\\\/palermo2\\\/#website\",\"url\":\"https:\\\/\\\/www.consorziobonifica.it\\\/palermo2\\\/\",\"name\":\"Consorzio di Bonifica Palermo 2\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.consorziobonifica.it\\\/palermo2\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.consorziobonifica.it\\\/palermo2\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.consorziobonifica.it\\\/palermo2\\\/#organization\",\"name\":\"Consorzio di bonifica 2 Palermo\",\"url\":\"https:\\\/\\\/www.consorziobonifica.it\\\/palermo2\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.consorziobonifica.it\\\/palermo2\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.consorziobonifica.it\\\/palermo2\\\/wp-content\\\/uploads\\\/2019\\\/11\\\/logo-consorzio.png\",\"contentUrl\":\"https:\\\/\\\/www.consorziobonifica.it\\\/palermo2\\\/wp-content\\\/uploads\\\/2019\\\/11\\\/logo-consorzio.png\",\"width\":350,\"height\":196,\"caption\":\"Consorzio di bonifica 2 Palermo\"},\"image\":{\"@id\":\"https:\\\/\\\/www.consorziobonifica.it\\\/palermo2\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"OCDPC 558\/2018 \"primi interventi urgenti di protezione civile in conseguenza degli eccezionale eventi meteorologici che hanno interessato le regioni Calabria, Emilia Romagna, Friuli, Lazio, Lombardia Toscana, Sardegna, Sicilia, Veneto e delle Provincie autonome di Trento e Bolzano colpite dagli eccezionali eventi metereologici verificatisi a partire dal mese di ottobre 2018\". Pagamento, a seguito affidamento diretto, ai sensi dell'art. 36, comma 2, lettera a) del D.Lgs. 50 del 18 aprile 2016 e ss.mm.ii., della fonitura di valvole a farfalla, per le camere di manovra, ubicate negli impianti consortili, di cui al COD. SI_PA_00975 (COMUNE DI MISILMERI), alla ditta Idroconnect di Fabio Campagna. [SMART CIG]: Z6329F14F7 - CUP: I65D19000050001. - Consorzio di Bonifica Palermo 2","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.consorziobonifica.it\/palermo2\/amm_trasparente\/ocdpc-558-2018-primi-interventi-urgenti-di-protezione-civile-in-conseguenza-degli-eccezionale-eventi-meteorologici-che-hanno-interessato-le-regioni-calabria-emilia-romagna-friuli-lazio-lombardia-3\/","og_locale":"it_IT","og_type":"article","og_title":"OCDPC 558\/2018 \"primi interventi urgenti di protezione civile in conseguenza degli eccezionale eventi meteorologici che hanno interessato le regioni Calabria, Emilia Romagna, Friuli, Lazio, Lombardia Toscana, Sardegna, Sicilia, Veneto e delle Provincie autonome di Trento e Bolzano colpite dagli eccezionali eventi metereologici verificatisi a partire dal mese di ottobre 2018\". Pagamento, a seguito affidamento diretto, ai sensi dell'art. 36, comma 2, lettera a) del D.Lgs. 50 del 18 aprile 2016 e ss.mm.ii., della fonitura di valvole a farfalla, per le camere di manovra, ubicate negli impianti consortili, di cui al COD. SI_PA_00975 (COMUNE DI MISILMERI), alla ditta Idroconnect di Fabio Campagna. [SMART CIG]: Z6329F14F7 - CUP: I65D19000050001. - Consorzio di Bonifica Palermo 2","og_url":"https:\/\/www.consorziobonifica.it\/palermo2\/amm_trasparente\/ocdpc-558-2018-primi-interventi-urgenti-di-protezione-civile-in-conseguenza-degli-eccezionale-eventi-meteorologici-che-hanno-interessato-le-regioni-calabria-emilia-romagna-friuli-lazio-lombardia-3\/","og_site_name":"Consorzio di Bonifica Palermo 2","article_modified_time":"2020-06-10T12:53:09+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.consorziobonifica.it\/palermo2\/amm_trasparente\/ocdpc-558-2018-primi-interventi-urgenti-di-protezione-civile-in-conseguenza-degli-eccezionale-eventi-meteorologici-che-hanno-interessato-le-regioni-calabria-emilia-romagna-friuli-lazio-lombardia-3\/","url":"https:\/\/www.consorziobonifica.it\/palermo2\/amm_trasparente\/ocdpc-558-2018-primi-interventi-urgenti-di-protezione-civile-in-conseguenza-degli-eccezionale-eventi-meteorologici-che-hanno-interessato-le-regioni-calabria-emilia-romagna-friuli-lazio-lombardia-3\/","name":"OCDPC 558\/2018 \"primi interventi urgenti di protezione civile in conseguenza degli eccezionale eventi meteorologici che hanno interessato le regioni Calabria, Emilia Romagna, Friuli, Lazio, Lombardia Toscana, Sardegna, Sicilia, Veneto e delle Provincie autonome di Trento e Bolzano colpite dagli eccezionali eventi metereologici verificatisi a partire dal mese di ottobre 2018\". Pagamento, a seguito affidamento diretto, ai sensi dell'art. 36, comma 2, lettera a) del D.Lgs. 50 del 18 aprile 2016 e ss.mm.ii., della fonitura di valvole a farfalla, per le camere di manovra, ubicate negli impianti consortili, di cui al COD. SI_PA_00975 (COMUNE DI MISILMERI), alla ditta Idroconnect di Fabio Campagna. [SMART CIG]: Z6329F14F7 - CUP: I65D19000050001. - Consorzio di Bonifica Palermo 2","isPartOf":{"@id":"https:\/\/www.consorziobonifica.it\/palermo2\/#website"},"datePublished":"2020-06-10T12:53:08+00:00","dateModified":"2020-06-10T12:53:09+00:00","breadcrumb":{"@id":"https:\/\/www.consorziobonifica.it\/palermo2\/amm_trasparente\/ocdpc-558-2018-primi-interventi-urgenti-di-protezione-civile-in-conseguenza-degli-eccezionale-eventi-meteorologici-che-hanno-interessato-le-regioni-calabria-emilia-romagna-friuli-lazio-lombardia-3\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.consorziobonifica.it\/palermo2\/amm_trasparente\/ocdpc-558-2018-primi-interventi-urgenti-di-protezione-civile-in-conseguenza-degli-eccezionale-eventi-meteorologici-che-hanno-interessato-le-regioni-calabria-emilia-romagna-friuli-lazio-lombardia-3\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.consorziobonifica.it\/palermo2\/amm_trasparente\/ocdpc-558-2018-primi-interventi-urgenti-di-protezione-civile-in-conseguenza-degli-eccezionale-eventi-meteorologici-che-hanno-interessato-le-regioni-calabria-emilia-romagna-friuli-lazio-lombardia-3\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.consorziobonifica.it\/palermo2\/"},{"@type":"ListItem","position":2,"name":"OCDPC 558\/2018 &#8220;primi interventi urgenti di protezione civile in conseguenza degli eccezionale eventi meteorologici che hanno interessato le regioni Calabria, Emilia Romagna, Friuli, Lazio, Lombardia Toscana, Sardegna, Sicilia, Veneto e delle Provincie autonome di Trento e Bolzano colpite dagli eccezionali eventi metereologici verificatisi a partire dal mese di ottobre 2018&#8221;. Pagamento, a seguito affidamento diretto, ai sensi dell&#8217;art. 36, comma 2, lettera a) del D.Lgs. 50 del 18 aprile 2016 e ss.mm.ii., della fonitura di valvole a farfalla, per le camere di manovra, ubicate negli impianti consortili, di cui al COD. SI_PA_00975 (COMUNE DI MISILMERI), alla ditta Idroconnect di Fabio Campagna. [SMART CIG]: Z6329F14F7 &#8211; CUP: I65D19000050001."}]},{"@type":"WebSite","@id":"https:\/\/www.consorziobonifica.it\/palermo2\/#website","url":"https:\/\/www.consorziobonifica.it\/palermo2\/","name":"Consorzio di Bonifica Palermo 2","description":"","publisher":{"@id":"https:\/\/www.consorziobonifica.it\/palermo2\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.consorziobonifica.it\/palermo2\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.consorziobonifica.it\/palermo2\/#organization","name":"Consorzio di bonifica 2 Palermo","url":"https:\/\/www.consorziobonifica.it\/palermo2\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.consorziobonifica.it\/palermo2\/#\/schema\/logo\/image\/","url":"https:\/\/www.consorziobonifica.it\/palermo2\/wp-content\/uploads\/2019\/11\/logo-consorzio.png","contentUrl":"https:\/\/www.consorziobonifica.it\/palermo2\/wp-content\/uploads\/2019\/11\/logo-consorzio.png","width":350,"height":196,"caption":"Consorzio di bonifica 2 Palermo"},"image":{"@id":"https:\/\/www.consorziobonifica.it\/palermo2\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.consorziobonifica.it\/palermo2\/wp-json\/wp\/v2\/amm_trasparente\/16946","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.consorziobonifica.it\/palermo2\/wp-json\/wp\/v2\/amm_trasparente"}],"about":[{"href":"https:\/\/www.consorziobonifica.it\/palermo2\/wp-json\/wp\/v2\/types\/amm_trasparente"}],"wp:attachment":[{"href":"https:\/\/www.consorziobonifica.it\/palermo2\/wp-json\/wp\/v2\/media?parent=16946"}],"wp:term":[{"taxonomy":"categoria_albo_pretorio","embeddable":true,"href":"https:\/\/www.consorziobonifica.it\/palermo2\/wp-json\/wp\/v2\/categoria_albo_pretorio?post=16946"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}