{"id":16956,"date":"2020-06-10T15:25:47","date_gmt":"2020-06-10T13:25:47","guid":{"rendered":"http:\/\/www.consorziobonifica.it\/palermo2\/?post_type=amm_trasparente&#038;p=16956"},"modified":"2020-06-10T15:25:47","modified_gmt":"2020-06-10T13:25:47","slug":"liquidazione-e-pagamento-a-seguito-di-affidamento-diretto-ai-sensi-dellart-36-comma-2-lettera-a-del-d-lgs-n-50-del-18-aprile-2016-e-ss-mm-ii-delle-riparazioni-meccaniche-per-i-mezzi-con","status":"publish","type":"amm_trasparente","link":"https:\/\/www.consorziobonifica.it\/palermo2\/amm_trasparente\/liquidazione-e-pagamento-a-seguito-di-affidamento-diretto-ai-sensi-dellart-36-comma-2-lettera-a-del-d-lgs-n-50-del-18-aprile-2016-e-ss-mm-ii-delle-riparazioni-meccaniche-per-i-mezzi-con\/","title":{"rendered":"Liquidazione e pagamento, a seguito di affidamento diretto, ai sensi dell&#8217;art. 36 comma 2 lettera a) del D.Lgs. n\u00b0 50 del 18 aprile 2016 e ss.mm.ii., delle riparazioni meccaniche per i mezzi consortili, a servizio della manutenzione degli impianti consortili, alla ditta Officina meccanica F,lli Ganguzza &#038; C. s.n.c.. [SMART CIG]: Z332B0094F."},"content":{"rendered":"","protected":false},"featured_media":0,"template":"","meta":{"_acf_changed":false,"_lmt_disableupdate":"","_lmt_disable":""},"categoria_albo_pretorio":[318],"class_list":["post-16956","amm_trasparente","type-amm_trasparente","status-publish","hentry","categoria_albo_pretorio-provvedimenti-dirigenti"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Liquidazione e pagamento, a seguito di affidamento diretto, ai sensi dell&#039;art. 36 comma 2 lettera a) del D.Lgs. n\u00b0 50 del 18 aprile 2016 e ss.mm.ii., delle riparazioni meccaniche per i mezzi consortili, a servizio della manutenzione degli impianti consortili, alla ditta Officina meccanica F,lli Ganguzza &amp; C. s.n.c.. [SMART CIG]: Z332B0094F. - Consorzio di Bonifica Palermo 2<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.consorziobonifica.it\/palermo2\/amm_trasparente\/liquidazione-e-pagamento-a-seguito-di-affidamento-diretto-ai-sensi-dellart-36-comma-2-lettera-a-del-d-lgs-n-50-del-18-aprile-2016-e-ss-mm-ii-delle-riparazioni-meccaniche-per-i-mezzi-con\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Liquidazione e pagamento, a seguito di affidamento diretto, ai sensi dell&#039;art. 36 comma 2 lettera a) del D.Lgs. n\u00b0 50 del 18 aprile 2016 e ss.mm.ii., delle riparazioni meccaniche per i mezzi consortili, a servizio della manutenzione degli impianti consortili, alla ditta Officina meccanica F,lli Ganguzza &amp; C. s.n.c.. [SMART CIG]: Z332B0094F. - Consorzio di Bonifica Palermo 2\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.consorziobonifica.it\/palermo2\/amm_trasparente\/liquidazione-e-pagamento-a-seguito-di-affidamento-diretto-ai-sensi-dellart-36-comma-2-lettera-a-del-d-lgs-n-50-del-18-aprile-2016-e-ss-mm-ii-delle-riparazioni-meccaniche-per-i-mezzi-con\/\" \/>\n<meta property=\"og:site_name\" content=\"Consorzio di Bonifica Palermo 2\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.consorziobonifica.it\\\/palermo2\\\/amm_trasparente\\\/liquidazione-e-pagamento-a-seguito-di-affidamento-diretto-ai-sensi-dellart-36-comma-2-lettera-a-del-d-lgs-n-50-del-18-aprile-2016-e-ss-mm-ii-delle-riparazioni-meccaniche-per-i-mezzi-con\\\/\",\"url\":\"https:\\\/\\\/www.consorziobonifica.it\\\/palermo2\\\/amm_trasparente\\\/liquidazione-e-pagamento-a-seguito-di-affidamento-diretto-ai-sensi-dellart-36-comma-2-lettera-a-del-d-lgs-n-50-del-18-aprile-2016-e-ss-mm-ii-delle-riparazioni-meccaniche-per-i-mezzi-con\\\/\",\"name\":\"Liquidazione e pagamento, a seguito di affidamento diretto, ai sensi dell'art. 36 comma 2 lettera a) del D.Lgs. n\u00b0 50 del 18 aprile 2016 e ss.mm.ii., delle riparazioni meccaniche per i mezzi consortili, a servizio della manutenzione degli impianti consortili, alla ditta Officina meccanica F,lli Ganguzza & C. s.n.c.. [SMART CIG]: Z332B0094F. - Consorzio di Bonifica Palermo 2\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.consorziobonifica.it\\\/palermo2\\\/#website\"},\"datePublished\":\"2020-06-10T13:25:47+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.consorziobonifica.it\\\/palermo2\\\/amm_trasparente\\\/liquidazione-e-pagamento-a-seguito-di-affidamento-diretto-ai-sensi-dellart-36-comma-2-lettera-a-del-d-lgs-n-50-del-18-aprile-2016-e-ss-mm-ii-delle-riparazioni-meccaniche-per-i-mezzi-con\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.consorziobonifica.it\\\/palermo2\\\/amm_trasparente\\\/liquidazione-e-pagamento-a-seguito-di-affidamento-diretto-ai-sensi-dellart-36-comma-2-lettera-a-del-d-lgs-n-50-del-18-aprile-2016-e-ss-mm-ii-delle-riparazioni-meccaniche-per-i-mezzi-con\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.consorziobonifica.it\\\/palermo2\\\/amm_trasparente\\\/liquidazione-e-pagamento-a-seguito-di-affidamento-diretto-ai-sensi-dellart-36-comma-2-lettera-a-del-d-lgs-n-50-del-18-aprile-2016-e-ss-mm-ii-delle-riparazioni-meccaniche-per-i-mezzi-con\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.consorziobonifica.it\\\/palermo2\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Liquidazione e pagamento, a seguito di affidamento diretto, ai sensi dell&#8217;art. 36 comma 2 lettera a) del D.Lgs. n\u00b0 50 del 18 aprile 2016 e ss.mm.ii., delle riparazioni meccaniche per i mezzi consortili, a servizio della manutenzione degli impianti consortili, alla ditta Officina meccanica F,lli Ganguzza &#038; C. s.n.c.. [SMART CIG]: Z332B0094F.\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.consorziobonifica.it\\\/palermo2\\\/#website\",\"url\":\"https:\\\/\\\/www.consorziobonifica.it\\\/palermo2\\\/\",\"name\":\"Consorzio di Bonifica Palermo 2\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.consorziobonifica.it\\\/palermo2\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.consorziobonifica.it\\\/palermo2\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.consorziobonifica.it\\\/palermo2\\\/#organization\",\"name\":\"Consorzio di bonifica 2 Palermo\",\"url\":\"https:\\\/\\\/www.consorziobonifica.it\\\/palermo2\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.consorziobonifica.it\\\/palermo2\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.consorziobonifica.it\\\/palermo2\\\/wp-content\\\/uploads\\\/2019\\\/11\\\/logo-consorzio.png\",\"contentUrl\":\"https:\\\/\\\/www.consorziobonifica.it\\\/palermo2\\\/wp-content\\\/uploads\\\/2019\\\/11\\\/logo-consorzio.png\",\"width\":350,\"height\":196,\"caption\":\"Consorzio di bonifica 2 Palermo\"},\"image\":{\"@id\":\"https:\\\/\\\/www.consorziobonifica.it\\\/palermo2\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Liquidazione e pagamento, a seguito di affidamento diretto, ai sensi dell'art. 36 comma 2 lettera a) del D.Lgs. n\u00b0 50 del 18 aprile 2016 e ss.mm.ii., delle riparazioni meccaniche per i mezzi consortili, a servizio della manutenzione degli impianti consortili, alla ditta Officina meccanica F,lli Ganguzza & C. s.n.c.. [SMART CIG]: Z332B0094F. - Consorzio di Bonifica Palermo 2","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.consorziobonifica.it\/palermo2\/amm_trasparente\/liquidazione-e-pagamento-a-seguito-di-affidamento-diretto-ai-sensi-dellart-36-comma-2-lettera-a-del-d-lgs-n-50-del-18-aprile-2016-e-ss-mm-ii-delle-riparazioni-meccaniche-per-i-mezzi-con\/","og_locale":"it_IT","og_type":"article","og_title":"Liquidazione e pagamento, a seguito di affidamento diretto, ai sensi dell'art. 36 comma 2 lettera a) del D.Lgs. n\u00b0 50 del 18 aprile 2016 e ss.mm.ii., delle riparazioni meccaniche per i mezzi consortili, a servizio della manutenzione degli impianti consortili, alla ditta Officina meccanica F,lli Ganguzza & C. s.n.c.. [SMART CIG]: Z332B0094F. - Consorzio di Bonifica Palermo 2","og_url":"https:\/\/www.consorziobonifica.it\/palermo2\/amm_trasparente\/liquidazione-e-pagamento-a-seguito-di-affidamento-diretto-ai-sensi-dellart-36-comma-2-lettera-a-del-d-lgs-n-50-del-18-aprile-2016-e-ss-mm-ii-delle-riparazioni-meccaniche-per-i-mezzi-con\/","og_site_name":"Consorzio di Bonifica Palermo 2","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.consorziobonifica.it\/palermo2\/amm_trasparente\/liquidazione-e-pagamento-a-seguito-di-affidamento-diretto-ai-sensi-dellart-36-comma-2-lettera-a-del-d-lgs-n-50-del-18-aprile-2016-e-ss-mm-ii-delle-riparazioni-meccaniche-per-i-mezzi-con\/","url":"https:\/\/www.consorziobonifica.it\/palermo2\/amm_trasparente\/liquidazione-e-pagamento-a-seguito-di-affidamento-diretto-ai-sensi-dellart-36-comma-2-lettera-a-del-d-lgs-n-50-del-18-aprile-2016-e-ss-mm-ii-delle-riparazioni-meccaniche-per-i-mezzi-con\/","name":"Liquidazione e pagamento, a seguito di affidamento diretto, ai sensi dell'art. 36 comma 2 lettera a) del D.Lgs. n\u00b0 50 del 18 aprile 2016 e ss.mm.ii., delle riparazioni meccaniche per i mezzi consortili, a servizio della manutenzione degli impianti consortili, alla ditta Officina meccanica F,lli Ganguzza & C. s.n.c.. [SMART CIG]: Z332B0094F. - Consorzio di Bonifica Palermo 2","isPartOf":{"@id":"https:\/\/www.consorziobonifica.it\/palermo2\/#website"},"datePublished":"2020-06-10T13:25:47+00:00","breadcrumb":{"@id":"https:\/\/www.consorziobonifica.it\/palermo2\/amm_trasparente\/liquidazione-e-pagamento-a-seguito-di-affidamento-diretto-ai-sensi-dellart-36-comma-2-lettera-a-del-d-lgs-n-50-del-18-aprile-2016-e-ss-mm-ii-delle-riparazioni-meccaniche-per-i-mezzi-con\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.consorziobonifica.it\/palermo2\/amm_trasparente\/liquidazione-e-pagamento-a-seguito-di-affidamento-diretto-ai-sensi-dellart-36-comma-2-lettera-a-del-d-lgs-n-50-del-18-aprile-2016-e-ss-mm-ii-delle-riparazioni-meccaniche-per-i-mezzi-con\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.consorziobonifica.it\/palermo2\/amm_trasparente\/liquidazione-e-pagamento-a-seguito-di-affidamento-diretto-ai-sensi-dellart-36-comma-2-lettera-a-del-d-lgs-n-50-del-18-aprile-2016-e-ss-mm-ii-delle-riparazioni-meccaniche-per-i-mezzi-con\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.consorziobonifica.it\/palermo2\/"},{"@type":"ListItem","position":2,"name":"Liquidazione e pagamento, a seguito di affidamento diretto, ai sensi dell&#8217;art. 36 comma 2 lettera a) del D.Lgs. n\u00b0 50 del 18 aprile 2016 e ss.mm.ii., delle riparazioni meccaniche per i mezzi consortili, a servizio della manutenzione degli impianti consortili, alla ditta Officina meccanica F,lli Ganguzza &#038; C. s.n.c.. [SMART CIG]: Z332B0094F."}]},{"@type":"WebSite","@id":"https:\/\/www.consorziobonifica.it\/palermo2\/#website","url":"https:\/\/www.consorziobonifica.it\/palermo2\/","name":"Consorzio di Bonifica Palermo 2","description":"","publisher":{"@id":"https:\/\/www.consorziobonifica.it\/palermo2\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.consorziobonifica.it\/palermo2\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.consorziobonifica.it\/palermo2\/#organization","name":"Consorzio di bonifica 2 Palermo","url":"https:\/\/www.consorziobonifica.it\/palermo2\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.consorziobonifica.it\/palermo2\/#\/schema\/logo\/image\/","url":"https:\/\/www.consorziobonifica.it\/palermo2\/wp-content\/uploads\/2019\/11\/logo-consorzio.png","contentUrl":"https:\/\/www.consorziobonifica.it\/palermo2\/wp-content\/uploads\/2019\/11\/logo-consorzio.png","width":350,"height":196,"caption":"Consorzio di bonifica 2 Palermo"},"image":{"@id":"https:\/\/www.consorziobonifica.it\/palermo2\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.consorziobonifica.it\/palermo2\/wp-json\/wp\/v2\/amm_trasparente\/16956","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.consorziobonifica.it\/palermo2\/wp-json\/wp\/v2\/amm_trasparente"}],"about":[{"href":"https:\/\/www.consorziobonifica.it\/palermo2\/wp-json\/wp\/v2\/types\/amm_trasparente"}],"wp:attachment":[{"href":"https:\/\/www.consorziobonifica.it\/palermo2\/wp-json\/wp\/v2\/media?parent=16956"}],"wp:term":[{"taxonomy":"categoria_albo_pretorio","embeddable":true,"href":"https:\/\/www.consorziobonifica.it\/palermo2\/wp-json\/wp\/v2\/categoria_albo_pretorio?post=16956"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}