{"id":17058,"date":"2020-06-29T14:14:25","date_gmt":"2020-06-29T12:14:25","guid":{"rendered":"http:\/\/www.consorziobonifica.it\/palermo2\/?post_type=amm_trasparente&#038;p=17058"},"modified":"2020-06-29T14:14:26","modified_gmt":"2020-06-29T12:14:26","slug":"utilizzazione-integrale-delle-acque-invasate-nel-serbatotio-di-garcia-sul-fiume-belice-sinistro-opere-di-distribuzione-irrigue-zone-iii-e-iv-b-liquidazione-e-pagamento-a-favore-dellimpresa-r","status":"publish","type":"amm_trasparente","link":"https:\/\/www.consorziobonifica.it\/palermo2\/amm_trasparente\/utilizzazione-integrale-delle-acque-invasate-nel-serbatotio-di-garcia-sul-fiume-belice-sinistro-opere-di-distribuzione-irrigue-zone-iii-e-iv-b-liquidazione-e-pagamento-a-favore-dellimpresa-r\/","title":{"rendered":"&#8220;Utilizzazione integrale delle acque invasate nel serbatotio di Garcia sul Fiume Belice Sinistro &#8211; Opere di distribuzione irrigue zone III e IV\/B&#8221;. Liquidazione e pagamento, a favore dell&#8217;impresa Russotto S.r.l., con sede in Via Aldo Moro n. 2 &#8211; 90020 San Giovanni Gemini (AG), per interessi legali e moratori dovuti a ritardato pagamento. CUP: I93H10000200001 CIG: 6327448744."},"content":{"rendered":"","protected":false},"featured_media":0,"template":"","meta":{"_acf_changed":false,"_lmt_disableupdate":"","_lmt_disable":""},"categoria_albo_pretorio":[318],"class_list":["post-17058","amm_trasparente","type-amm_trasparente","status-publish","hentry","categoria_albo_pretorio-provvedimenti-dirigenti"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>&quot;Utilizzazione integrale delle acque invasate nel serbatotio di Garcia sul Fiume Belice Sinistro - Opere di distribuzione irrigue zone III e IV\/B&quot;. Liquidazione e pagamento, a favore dell&#039;impresa Russotto S.r.l., con sede in Via Aldo Moro n. 2 - 90020 San Giovanni Gemini (AG), per interessi legali e moratori dovuti a ritardato pagamento. CUP: I93H10000200001 CIG: 6327448744. - Consorzio di Bonifica Palermo 2<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.consorziobonifica.it\/palermo2\/amm_trasparente\/utilizzazione-integrale-delle-acque-invasate-nel-serbatotio-di-garcia-sul-fiume-belice-sinistro-opere-di-distribuzione-irrigue-zone-iii-e-iv-b-liquidazione-e-pagamento-a-favore-dellimpresa-r\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"&quot;Utilizzazione integrale delle acque invasate nel serbatotio di Garcia sul Fiume Belice Sinistro - Opere di distribuzione irrigue zone III e IV\/B&quot;. Liquidazione e pagamento, a favore dell&#039;impresa Russotto S.r.l., con sede in Via Aldo Moro n. 2 - 90020 San Giovanni Gemini (AG), per interessi legali e moratori dovuti a ritardato pagamento. CUP: I93H10000200001 CIG: 6327448744. - Consorzio di Bonifica Palermo 2\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.consorziobonifica.it\/palermo2\/amm_trasparente\/utilizzazione-integrale-delle-acque-invasate-nel-serbatotio-di-garcia-sul-fiume-belice-sinistro-opere-di-distribuzione-irrigue-zone-iii-e-iv-b-liquidazione-e-pagamento-a-favore-dellimpresa-r\/\" \/>\n<meta property=\"og:site_name\" content=\"Consorzio di Bonifica Palermo 2\" \/>\n<meta property=\"article:modified_time\" content=\"2020-06-29T12:14:26+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.consorziobonifica.it\\\/palermo2\\\/amm_trasparente\\\/utilizzazione-integrale-delle-acque-invasate-nel-serbatotio-di-garcia-sul-fiume-belice-sinistro-opere-di-distribuzione-irrigue-zone-iii-e-iv-b-liquidazione-e-pagamento-a-favore-dellimpresa-r\\\/\",\"url\":\"https:\\\/\\\/www.consorziobonifica.it\\\/palermo2\\\/amm_trasparente\\\/utilizzazione-integrale-delle-acque-invasate-nel-serbatotio-di-garcia-sul-fiume-belice-sinistro-opere-di-distribuzione-irrigue-zone-iii-e-iv-b-liquidazione-e-pagamento-a-favore-dellimpresa-r\\\/\",\"name\":\"\\\"Utilizzazione integrale delle acque invasate nel serbatotio di Garcia sul Fiume Belice Sinistro - Opere di distribuzione irrigue zone III e IV\\\/B\\\". Liquidazione e pagamento, a favore dell'impresa Russotto S.r.l., con sede in Via Aldo Moro n. 2 - 90020 San Giovanni Gemini (AG), per interessi legali e moratori dovuti a ritardato pagamento. CUP: I93H10000200001 CIG: 6327448744. - Consorzio di Bonifica Palermo 2\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.consorziobonifica.it\\\/palermo2\\\/#website\"},\"datePublished\":\"2020-06-29T12:14:25+00:00\",\"dateModified\":\"2020-06-29T12:14:26+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.consorziobonifica.it\\\/palermo2\\\/amm_trasparente\\\/utilizzazione-integrale-delle-acque-invasate-nel-serbatotio-di-garcia-sul-fiume-belice-sinistro-opere-di-distribuzione-irrigue-zone-iii-e-iv-b-liquidazione-e-pagamento-a-favore-dellimpresa-r\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.consorziobonifica.it\\\/palermo2\\\/amm_trasparente\\\/utilizzazione-integrale-delle-acque-invasate-nel-serbatotio-di-garcia-sul-fiume-belice-sinistro-opere-di-distribuzione-irrigue-zone-iii-e-iv-b-liquidazione-e-pagamento-a-favore-dellimpresa-r\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.consorziobonifica.it\\\/palermo2\\\/amm_trasparente\\\/utilizzazione-integrale-delle-acque-invasate-nel-serbatotio-di-garcia-sul-fiume-belice-sinistro-opere-di-distribuzione-irrigue-zone-iii-e-iv-b-liquidazione-e-pagamento-a-favore-dellimpresa-r\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.consorziobonifica.it\\\/palermo2\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"&#8220;Utilizzazione integrale delle acque invasate nel serbatotio di Garcia sul Fiume Belice Sinistro &#8211; Opere di distribuzione irrigue zone III e IV\\\/B&#8221;. Liquidazione e pagamento, a favore dell&#8217;impresa Russotto S.r.l., con sede in Via Aldo Moro n. 2 &#8211; 90020 San Giovanni Gemini (AG), per interessi legali e moratori dovuti a ritardato pagamento. CUP: I93H10000200001 CIG: 6327448744.\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.consorziobonifica.it\\\/palermo2\\\/#website\",\"url\":\"https:\\\/\\\/www.consorziobonifica.it\\\/palermo2\\\/\",\"name\":\"Consorzio di Bonifica Palermo 2\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.consorziobonifica.it\\\/palermo2\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.consorziobonifica.it\\\/palermo2\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.consorziobonifica.it\\\/palermo2\\\/#organization\",\"name\":\"Consorzio di bonifica 2 Palermo\",\"url\":\"https:\\\/\\\/www.consorziobonifica.it\\\/palermo2\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.consorziobonifica.it\\\/palermo2\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.consorziobonifica.it\\\/palermo2\\\/wp-content\\\/uploads\\\/2019\\\/11\\\/logo-consorzio.png\",\"contentUrl\":\"https:\\\/\\\/www.consorziobonifica.it\\\/palermo2\\\/wp-content\\\/uploads\\\/2019\\\/11\\\/logo-consorzio.png\",\"width\":350,\"height\":196,\"caption\":\"Consorzio di bonifica 2 Palermo\"},\"image\":{\"@id\":\"https:\\\/\\\/www.consorziobonifica.it\\\/palermo2\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\"Utilizzazione integrale delle acque invasate nel serbatotio di Garcia sul Fiume Belice Sinistro - Opere di distribuzione irrigue zone III e IV\/B\". Liquidazione e pagamento, a favore dell'impresa Russotto S.r.l., con sede in Via Aldo Moro n. 2 - 90020 San Giovanni Gemini (AG), per interessi legali e moratori dovuti a ritardato pagamento. CUP: I93H10000200001 CIG: 6327448744. - Consorzio di Bonifica Palermo 2","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.consorziobonifica.it\/palermo2\/amm_trasparente\/utilizzazione-integrale-delle-acque-invasate-nel-serbatotio-di-garcia-sul-fiume-belice-sinistro-opere-di-distribuzione-irrigue-zone-iii-e-iv-b-liquidazione-e-pagamento-a-favore-dellimpresa-r\/","og_locale":"it_IT","og_type":"article","og_title":"\"Utilizzazione integrale delle acque invasate nel serbatotio di Garcia sul Fiume Belice Sinistro - Opere di distribuzione irrigue zone III e IV\/B\". Liquidazione e pagamento, a favore dell'impresa Russotto S.r.l., con sede in Via Aldo Moro n. 2 - 90020 San Giovanni Gemini (AG), per interessi legali e moratori dovuti a ritardato pagamento. CUP: I93H10000200001 CIG: 6327448744. - Consorzio di Bonifica Palermo 2","og_url":"https:\/\/www.consorziobonifica.it\/palermo2\/amm_trasparente\/utilizzazione-integrale-delle-acque-invasate-nel-serbatotio-di-garcia-sul-fiume-belice-sinistro-opere-di-distribuzione-irrigue-zone-iii-e-iv-b-liquidazione-e-pagamento-a-favore-dellimpresa-r\/","og_site_name":"Consorzio di Bonifica Palermo 2","article_modified_time":"2020-06-29T12:14:26+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.consorziobonifica.it\/palermo2\/amm_trasparente\/utilizzazione-integrale-delle-acque-invasate-nel-serbatotio-di-garcia-sul-fiume-belice-sinistro-opere-di-distribuzione-irrigue-zone-iii-e-iv-b-liquidazione-e-pagamento-a-favore-dellimpresa-r\/","url":"https:\/\/www.consorziobonifica.it\/palermo2\/amm_trasparente\/utilizzazione-integrale-delle-acque-invasate-nel-serbatotio-di-garcia-sul-fiume-belice-sinistro-opere-di-distribuzione-irrigue-zone-iii-e-iv-b-liquidazione-e-pagamento-a-favore-dellimpresa-r\/","name":"\"Utilizzazione integrale delle acque invasate nel serbatotio di Garcia sul Fiume Belice Sinistro - Opere di distribuzione irrigue zone III e IV\/B\". Liquidazione e pagamento, a favore dell'impresa Russotto S.r.l., con sede in Via Aldo Moro n. 2 - 90020 San Giovanni Gemini (AG), per interessi legali e moratori dovuti a ritardato pagamento. CUP: I93H10000200001 CIG: 6327448744. - Consorzio di Bonifica Palermo 2","isPartOf":{"@id":"https:\/\/www.consorziobonifica.it\/palermo2\/#website"},"datePublished":"2020-06-29T12:14:25+00:00","dateModified":"2020-06-29T12:14:26+00:00","breadcrumb":{"@id":"https:\/\/www.consorziobonifica.it\/palermo2\/amm_trasparente\/utilizzazione-integrale-delle-acque-invasate-nel-serbatotio-di-garcia-sul-fiume-belice-sinistro-opere-di-distribuzione-irrigue-zone-iii-e-iv-b-liquidazione-e-pagamento-a-favore-dellimpresa-r\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.consorziobonifica.it\/palermo2\/amm_trasparente\/utilizzazione-integrale-delle-acque-invasate-nel-serbatotio-di-garcia-sul-fiume-belice-sinistro-opere-di-distribuzione-irrigue-zone-iii-e-iv-b-liquidazione-e-pagamento-a-favore-dellimpresa-r\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.consorziobonifica.it\/palermo2\/amm_trasparente\/utilizzazione-integrale-delle-acque-invasate-nel-serbatotio-di-garcia-sul-fiume-belice-sinistro-opere-di-distribuzione-irrigue-zone-iii-e-iv-b-liquidazione-e-pagamento-a-favore-dellimpresa-r\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.consorziobonifica.it\/palermo2\/"},{"@type":"ListItem","position":2,"name":"&#8220;Utilizzazione integrale delle acque invasate nel serbatotio di Garcia sul Fiume Belice Sinistro &#8211; Opere di distribuzione irrigue zone III e IV\/B&#8221;. Liquidazione e pagamento, a favore dell&#8217;impresa Russotto S.r.l., con sede in Via Aldo Moro n. 2 &#8211; 90020 San Giovanni Gemini (AG), per interessi legali e moratori dovuti a ritardato pagamento. CUP: I93H10000200001 CIG: 6327448744."}]},{"@type":"WebSite","@id":"https:\/\/www.consorziobonifica.it\/palermo2\/#website","url":"https:\/\/www.consorziobonifica.it\/palermo2\/","name":"Consorzio di Bonifica Palermo 2","description":"","publisher":{"@id":"https:\/\/www.consorziobonifica.it\/palermo2\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.consorziobonifica.it\/palermo2\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.consorziobonifica.it\/palermo2\/#organization","name":"Consorzio di bonifica 2 Palermo","url":"https:\/\/www.consorziobonifica.it\/palermo2\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.consorziobonifica.it\/palermo2\/#\/schema\/logo\/image\/","url":"https:\/\/www.consorziobonifica.it\/palermo2\/wp-content\/uploads\/2019\/11\/logo-consorzio.png","contentUrl":"https:\/\/www.consorziobonifica.it\/palermo2\/wp-content\/uploads\/2019\/11\/logo-consorzio.png","width":350,"height":196,"caption":"Consorzio di bonifica 2 Palermo"},"image":{"@id":"https:\/\/www.consorziobonifica.it\/palermo2\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.consorziobonifica.it\/palermo2\/wp-json\/wp\/v2\/amm_trasparente\/17058","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.consorziobonifica.it\/palermo2\/wp-json\/wp\/v2\/amm_trasparente"}],"about":[{"href":"https:\/\/www.consorziobonifica.it\/palermo2\/wp-json\/wp\/v2\/types\/amm_trasparente"}],"wp:attachment":[{"href":"https:\/\/www.consorziobonifica.it\/palermo2\/wp-json\/wp\/v2\/media?parent=17058"}],"wp:term":[{"taxonomy":"categoria_albo_pretorio","embeddable":true,"href":"https:\/\/www.consorziobonifica.it\/palermo2\/wp-json\/wp\/v2\/categoria_albo_pretorio?post=17058"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}